{"id":5605,"date":"2026-05-29T14:00:00","date_gmt":"2026-05-29T17:00:00","guid":{"rendered":"https:\/\/semapi.com.br\/?p=5605"},"modified":"2026-05-29T12:19:01","modified_gmt":"2026-05-29T15:19:01","slug":"expo-infrafm-2026-semapi-apresenta-solucoes-integradas","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/","title":{"rendered":"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A&nbsp;SEMAPI&nbsp;estar\u00e1 presente na Expo&nbsp;InfraFM&nbsp;2026, um dos principais eventos da Am\u00e9rica Latina voltados para&nbsp;Facility&nbsp;Management, infraestrutura, manuten\u00e7\u00e3o e tecnologia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante os tr\u00eas dias de feira, apresentaremos&nbsp;ao mercado&nbsp;nossas solu\u00e7\u00f5es integradas voltadas \u00e0 efici\u00eancia operacional, confiabilidade industrial e transforma\u00e7\u00e3o digital nas empresas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A participa\u00e7\u00e3o no evento refor\u00e7a o posicionamento da SEMAPI como uma empresa atua de forma estrat\u00e9gica em diferentes etapas da opera\u00e7\u00e3o industrial e corporativa, oferecendo solu\u00e7\u00f5es que conectam tecnologia, gest\u00e3o e intelig\u00eancia operacional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste ano, a SEMAPI\u00a0levar\u00e1\u00a0para\u00a0a\u00a0Expo\u00a0InfraFM\u00a0suas\u00a0tr\u00eas\u00a0principais\u00a0frentes\u00a0de atua\u00e7\u00e3o: manuten\u00e7\u00e3o preditiva,\u00a0gest\u00e3o\u00a0da\u00a0manuten\u00e7\u00e3o\u00a0com o\u00a0MANTec\u00a0e\u00a0gest\u00e3o\u00a0estrat\u00e9gica\u00a0de\u00a0suprimentos\u00a0com o USEMOL.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tecnologia&nbsp;aplicada&nbsp;\u00e0&nbsp;confiabilidade&nbsp;operacional<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A<a href=\"https:\/\/semapi.com.br\/es\/6-exemplos-de-manutencao-preditiva\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0manuten\u00e7\u00e3o\u00a0preditiva<\/a>\u00a0\u00e9\u00a0uma\u00a0das\u00a0principais\u00a0especialidades\u00a0da SEMAPI\u00a0e\u00a0estar\u00e1\u00a0em\u00a0destaque\u00a0durante\u00a0a\u00a0feira. Atrav\u00e9s de\u00a0tecnologias\u00a0e metodologias\u00a0voltadas\u00a0ao\u00a0monitoramento\u00a0da\u00a0condi\u00e7\u00e3o\u00a0de\u00a0ativos,\u00a0a\u00a0empresa\u00a0auxilia ind\u00fastrias\u00a0e\u00a0opera\u00e7\u00f5es\u00a0cr\u00edticas\u00a0na\u00a0identifica\u00e7\u00e3o\u00a0antecipada\u00a0de\u00a0falhas,\u00a0redu\u00e7\u00e3o\u00a0de\u00a0paradas\u00a0n\u00e3o\u00a0planejadas\u00a0e aumento\u00a0da\u00a0confiabilidade\u00a0operacional.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com\u00a0an\u00e1lises\u00a0t\u00e9cnicas\u00a0e\u00a0acompanhamento\u00a0cont\u00ednuo\u00a0de\u00a0equipamentos, a\u00a0SEMAPI\u00a0contribui para\u00a0que as empresas tomem\u00a0decis\u00f5es\u00a0mais\u00a0assertivas, reduzam\u00a0custos\u00a0com\u00a0manuten\u00e7\u00e3o\u00a0corretiva\u00a0e\u00a0ampliem a\u00a0vida\u00a0\u00fatil\u00a0de\u00a0seus ativos\u00a0industriais.\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>MANTec:&nbsp;gest\u00e3o&nbsp;da&nbsp;manuten\u00e7\u00e3o&nbsp;com&nbsp;mais&nbsp;controle&nbsp;e performance<\/strong>&nbsp;&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Outra\u00a0solu\u00e7\u00e3o\u00a0apresentada\u00a0durante\u00a0a\u00a0Expo\u00a0InfraFM\u00a0ser\u00e1\u00a0o\u00a0MANTec,\u00a0plataforma desenvolvida para apoiar empresas na\u00a0gest\u00e3o\u00a0da\u00a0manuten\u00e7\u00e3o\u00a0e dos\u00a0ativos\u00a0industriais.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O\u00a0sistema\u00a0foi\u00a0criado\u00a0para\u00a0oferecer\u00a0mais\u00a0controle,\u00a0organiza\u00e7\u00e3o\u00a0e\u00a0visibilidade\u00a0sobre\u00a0os\u00a0processos\u00a0de\u00a0manuten\u00e7\u00e3o, permitindo uma\u00a0gest\u00e3o\u00a0mais\u00a0estrat\u00e9gica\u00a0das\u00a0opera\u00e7\u00f5es.\u00a0Com o\u00a0MANTec, as\u00a0empresas\u00a0conseguem centralizar informa\u00e7\u00f5es,\u00a0acompanhar indicadores,\u00a0planejar\u00a0atividades\u00a0e\u00a0otimizar\u00a0recursos\u00a0de forma\u00a0integrada.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m\u00a0de\u00a0facilitar\u00a0a\u00a0rotina\u00a0operacional, o\u00a0MANTec\u00a0contribui\u00a0para a\u00a0tomada de\u00a0decis\u00e3o baseada em dados, promovendo maior efici\u00eancia\u00a0na\u00a0gest\u00e3o\u00a0dos\u00a0ativos e apoiando\u00a0iniciativas\u00a0de\u00a0melhoria cont\u00ednua.\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>USEMOL:&nbsp;efici\u00eancia&nbsp;e&nbsp;estrat\u00e9gia&nbsp;para a&nbsp;cadeia&nbsp;de&nbsp;suprimentos<\/strong>&nbsp;&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estaremos presentes tamb\u00e9m\u00a0com\u00a0o USEMOL, portal de\u00a0compras\u00a0e\u00a0suprimentos desenvolvido\u00a0para\u00a0transformar a forma\u00a0como\u00a0empresas\u00a0gerenciam aquisi\u00e7\u00f5es\u00a0e\u00a0\u00a0relacionamento\u00a0com\u00a0fornecedores.\u00a0A\u00a0plataforma\u00a0atua\u00a0como um\u00a0suporte\u00a0estrat\u00e9gico para\u00a0as\u00a0\u00e1reas\u00a0de\u00a0suprimentos, permitindo\u00a0mais\u00a0agilidade, controle\u00a0e\u00a0competitividade nos\u00a0processos\u00a0de compra.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre\u00a0os\u00a0recursos\u00a0dispon\u00edveis\u00a0est\u00e3o\u00a0funcionalidades\u00a0voltadas\u00a0para\u00a0gest\u00e3o\u00a0de\u00a0fornecedores, cota\u00e7\u00f5es, negocia\u00e7\u00f5es,\u00a0leil\u00e3o reverso\u00a0e\u00a0acompanhamento\u00a0de\u00a0processos\u00a0\u00a0de\u00a0aquisi\u00e7\u00e3o.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o USEMOL, as\u00a0empresas\u00a0conseguem aumentar\u00a0a\u00a0efici\u00eancia\u00a0operacional da\u00a0cadeia\u00a0de\u00a0suprimentos, reduzir\u00a0custos e\u00a0melhorar\u00a0a\u00a0transpar\u00eancia\u00a0das negocia\u00e7\u00f5es, alinhando\u00a0tecnologia\u00a0e\u00a0estrat\u00e9gia em\u00a0um\u00a0\u00fanico ambiente.\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solu\u00e7\u00f5es&nbsp;integradas&nbsp;para&nbsp;os&nbsp;desafios&nbsp;da&nbsp;ind\u00fastria&nbsp;e&nbsp;do&nbsp;Facility&nbsp;management<\/strong>&nbsp;&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00a0Expo\u00a0InfraFM\u00a0re\u00fane\u00a0profissionais,\u00a0gestores\u00a0e\u00a0empresas\u00a0que\u00a0buscam\u00a0inova\u00e7\u00e3o\u00a0e\u00a0novas\u00a0solu\u00e7\u00f5es\u00a0para\u00a0os\u00a0desafio do\u00a0setor,\u00a0tornando-se um\u00a0ambiente\u00a0estrat\u00e9gico\u00a0para troca\u00a0de\u00a0conhecimento,\u00a0networking e gera\u00e7\u00e3o de neg\u00f3cios.\u00a0\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Visite&nbsp;a SEMAPI&nbsp;na&nbsp;Expo&nbsp;InfraFM&nbsp;2026<\/strong>&nbsp;&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Convidamos\u00a0clientes,\u00a0parceiros\u00a0e\u00a0profissionais\u00a0do\u00a0setor\u00a0para\u00a0visitar\u00a0nosso\u00a0estande\u00a0durante\u00a0a\u00a0<a href=\"https:\/\/www.infrafm.com.br\/eventos\/205\/expo-infrafm-2026?utm_source=menu-portal-ifm\" target=\"_blank\" rel=\"noreferrer noopener\">Expo\u00a0InfraFM\u00a02026<\/a>\u00a0e\u00a0conhecer\u00a0de\u00a0perto\u00a0as\u00a0solu\u00e7\u00f5es\u00a0\u00a0voltadas\u00a0\u00e0\u00a0manuten\u00e7\u00e3o, gest\u00e3o\u00a0de\u00a0ativos\u00a0e\u00a0suprimentos.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccd Expo Center Norte \u2014 S\u00e3o Paulo\/SP&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcc5 09&nbsp;a&nbsp;11 de&nbsp;junho&nbsp;de 2026&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd59 Das 10h&nbsp;\u00e0s&nbsp;20h&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A&nbsp;SEMAPI&nbsp;estar\u00e1 presente na Expo&nbsp;InfraFM&nbsp;2026, um dos principais eventos da Am\u00e9rica Latina voltados para&nbsp;Facility&nbsp;Management, infraestrutura, manuten\u00e7\u00e3o e tecnologia.&nbsp; Durante os tr\u00eas dias de feira, apresentaremos&nbsp;ao mercado&nbsp;nossas solu\u00e7\u00f5es integradas voltadas \u00e0 efici\u00eancia operacional, confiabilidade industrial e transforma\u00e7\u00e3o digital nas empresas.&nbsp;&nbsp; A participa\u00e7\u00e3o no evento refor\u00e7a o posicionamento da SEMAPI como uma empresa atua de forma estrat\u00e9gica em [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":5607,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":21,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-5605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0<\/title>\n<meta name=\"description\" content=\"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0\" \/>\n<meta property=\"og:description\" content=\"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0\",\"datePublished\":\"2026-05-29T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/\"},\"wordCount\":652,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TEMPLATE-EMAIL-2026-2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/\",\"name\":\"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TEMPLATE-EMAIL-2026-2.jpg\",\"datePublished\":\"2026-05-29T17:00:00+00:00\",\"description\":\"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TEMPLATE-EMAIL-2026-2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/TEMPLATE-EMAIL-2026-2.jpg\",\"width\":1800,\"height\":800,\"caption\":\"Expo InfraFM 2026\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0","description":"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/","og_locale":"es_ES","og_type":"article","og_title":"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0","og_description":"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.","og_url":"https:\/\/semapi.com.br\/es\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/","og_site_name":"SEMAPI","article_published_time":"2026-05-29T17:00:00+00:00","og_image":[{"width":1800,"height":800,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0","datePublished":"2026-05-29T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/"},"wordCount":652,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/","url":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/","name":"Expo\u00a0InfraFM\u00a02026: SEMAPI apresenta solu\u00e7\u00f5es integradas para manuten\u00e7\u00e3o, gest\u00e3o e suprimentos\u00a0","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","datePublished":"2026-05-29T17:00:00+00:00","description":"A SEMAPI tem presen\u00e7a confirmada em todos os dias da Expo InfraFM 2026. Apresentando solu\u00e7\u00f5es de manuten\u00e7\u00e3o, gest\u00e3o e suprimentos.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/expo-infrafm-2026-semapi-apresenta-solucoes-integradas\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/05\/TEMPLATE-EMAIL-2026-2.jpg","width":1800,"height":800,"caption":"Expo InfraFM 2026"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=5605"}],"version-history":[{"count":4,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5605\/revisions"}],"predecessor-version":[{"id":5610,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5605\/revisions\/5610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/5607"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=5605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=5605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=5605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}