{"id":5366,"date":"2026-02-20T09:31:26","date_gmt":"2026-02-20T12:31:26","guid":{"rendered":"https:\/\/semapi.com.br\/?p=5366"},"modified":"2026-02-20T09:31:41","modified_gmt":"2026-02-20T12:31:41","slug":"reforma-tributaria-e-compras-o-que-muda-na-pratica","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/","title":{"rendered":"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A Reforma Tribut\u00e1ria vai transformar a forma como as empresas tomam decis\u00f5es de compra. Com novas regras de cr\u00e9dito e incid\u00eancia fiscal, analisar apenas o menor pre\u00e7o deixa de ser suficiente \u2014 e, em muitos casos, pode at\u00e9 representar um risco para a sa\u00fade financeira do neg\u00f3cio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na pr\u00e1tica, o <a href=\"https:\/\/semapi.com.br\/es\/reforma-tributaria-entenda-o-que-muda-a-partir-de-2026\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/reforma-tributaria-entenda-o-que-muda-a-partir-de-2026\/\">impacto tribut\u00e1rio<\/a> passa a influenciar diretamente o custo total da contrata\u00e7\u00e3o. Isso significa que decis\u00f5es superficiais, baseadas somente em valores aparentes, podem comprometer margens, competitividade e previsibilidade financeira. O cen\u00e1rio exige uma \u00e1rea de compras mais anal\u00edtica, capaz de interpretar dados fiscais e transformar compara\u00e7\u00f5es em decis\u00f5es estrat\u00e9gicas.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O novo papel das negocia\u00e7\u00f5es\u00a0\u00a0<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A mudan\u00e7a na l\u00f3gica tribut\u00e1ria altera a din\u00e2mica das <a href=\"https:\/\/semapi.com.br\/es\/cadastro-fornecedores-reforma-tributaria\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/cadastro-fornecedores-reforma-tributaria\/\">negocia\u00e7\u00f5es com fornecedores,<\/a> exigindo mais profundidade nas an\u00e1lises e maior integra\u00e7\u00e3o entre compras, financeiro e fiscal.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, ferramentas que antes eram vistas apenas como operacionais<a href=\"https:\/\/semapi.com.br\/es\/melhor-sistema-gestao-fornecedores\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/melhor-sistema-gestao-fornecedores\/\"> ganham relev\u00e2ncia estrat\u00e9gica.<\/a> O Mapa Comparativo, por exemplo, deixa de ser uma simples planilha de pre\u00e7os e passa a apoiar an\u00e1lises completas de custo total, oferecendo mais seguran\u00e7a para decis\u00f5es cr\u00edticas.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Webinar gratuito\u00a0<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para ajudar empresas a entender esse novo cen\u00e1rio,\u00a0o <a href=\"https:\/\/semapi.com.br\/es\/diferenciais-usemol\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/diferenciais-usemol\/\">portal de compras <\/a>USEMOL, em parceria com a\u00a0Ocre Capital e o Grupo Studio,\u00a0promovem um webinar gratuito que vai abordar:\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O cen\u00e1rio macro da Reforma Tribut\u00e1ria;\u00a0<\/li>\n\n\n\n<li>Como a nova l\u00f3gica tribut\u00e1ria impacta negocia\u00e7\u00f5es;\u00a0<\/li>\n\n\n\n<li>Como o Mapa Comparativo pode transformar an\u00e1lises de pre\u00e7o em an\u00e1lises estrat\u00e9gicas;\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Mais do que uma mudan\u00e7a regulat\u00f3ria, a Reforma Tribut\u00e1ria reposiciona <a href=\"https:\/\/semapi.com.br\/es\/diferenca-procurement-compras\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/diferenca-procurement-compras\/\">a \u00e1rea de compras <\/a>como pe\u00e7a-chave no resultado financeiro das organiza\u00e7\u00f5es. Quem se antecipar e estruturar an\u00e1lises mais inteligentes tende a ganhar vantagem competitiva.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea quer entender como virar o jogo com intelig\u00eancia fiscal e <a href=\"https:\/\/semapi.com.br\/es\/integracoes-com-sap\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/integracoes-com-sap\/\">an\u00e1lise estruturada,<\/a> este encontro foi pensado para voc\u00ea.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/Realize-o-sonho-da-casa-propria-imobiliaria-moderno-azul-post-do-instagram-1600-x-838-px-1920-x-1080-px.jpg\" alt=\"webinar\" class=\"wp-image-5367\" srcset=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/Realize-o-sonho-da-casa-propria-imobiliaria-moderno-azul-post-do-instagram-1600-x-838-px-1920-x-1080-px.jpg 800w, https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/Realize-o-sonho-da-casa-propria-imobiliaria-moderno-azul-post-do-instagram-1600-x-838-px-1920-x-1080-px-300x169.jpg 300w, https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/Realize-o-sonho-da-casa-propria-imobiliaria-moderno-azul-post-do-instagram-1600-x-838-px-1920-x-1080-px-768x432.jpg 768w, https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/Realize-o-sonho-da-casa-propria-imobiliaria-moderno-azul-post-do-instagram-1600-x-838-px-1920-x-1080-px-18x10.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Garanta sua vaga agora\u00a0clicando <a href=\"https:\/\/forms.office.com\/r\/He416QtmM6?origin=lprLink\" type=\"link\" id=\"https:\/\/forms.office.com\/r\/He416QtmM6?origin=lprLink\">aqui.\u00a0<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A Reforma Tribut\u00e1ria vai transformar a forma como as empresas tomam decis\u00f5es de compra. Com novas regras de cr\u00e9dito e incid\u00eancia fiscal, analisar apenas o menor pre\u00e7o deixa de ser suficiente \u2014 e, em muitos casos, pode at\u00e9 representar um risco para a sa\u00fade financeira do neg\u00f3cio.&nbsp; Na pr\u00e1tica, o impacto tribut\u00e1rio passa a influenciar [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":5368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":51,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-5366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"A Reforma Tribut\u00e1ria vai transformar a forma como as empresas tomam decis\u00f5es de compra. Com novas regras de cr\u00e9dito e incid\u00eancia fiscal, analisar apenas o menor pre\u00e7o deixa de ser suficiente \u2014 e, em muitos casos, pode at\u00e9 representar um risco para a sa\u00fade financeira do neg\u00f3cio.&nbsp; Na pr\u00e1tica, o impacto tribut\u00e1rio passa a influenciar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-20T12:31:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T12:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica\",\"datePublished\":\"2026-02-20T12:31:26+00:00\",\"dateModified\":\"2026-02-20T12:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/\"},\"wordCount\":346,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/supply2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/\",\"name\":\"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/supply2.jpg\",\"datePublished\":\"2026-02-20T12:31:26+00:00\",\"dateModified\":\"2026-02-20T12:31:41+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/reforma-tributaria-e-compras-o-que-muda-na-pratica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/supply2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/supply2.jpg\",\"width\":1024,\"height\":576,\"caption\":\"supply\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/","og_locale":"es_ES","og_type":"article","og_title":"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI","og_description":"A Reforma Tribut\u00e1ria vai transformar a forma como as empresas tomam decis\u00f5es de compra. Com novas regras de cr\u00e9dito e incid\u00eancia fiscal, analisar apenas o menor pre\u00e7o deixa de ser suficiente \u2014 e, em muitos casos, pode at\u00e9 representar um risco para a sa\u00fade financeira do neg\u00f3cio.&nbsp; Na pr\u00e1tica, o impacto tribut\u00e1rio passa a influenciar [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/","og_site_name":"SEMAPI","article_published_time":"2026-02-20T12:31:26+00:00","article_modified_time":"2026-02-20T12:31:41+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica","datePublished":"2026-02-20T12:31:26+00:00","dateModified":"2026-02-20T12:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/"},"wordCount":346,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/","url":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/","name":"Reforma Tribut\u00e1ria e compras: o que muda na pr\u00e1tica - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","datePublished":"2026-02-20T12:31:26+00:00","dateModified":"2026-02-20T12:31:41+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/reforma-tributaria-e-compras-o-que-muda-na-pratica\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/supply2.jpg","width":1024,"height":576,"caption":"supply"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=5366"}],"version-history":[{"count":2,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5366\/revisions"}],"predecessor-version":[{"id":5370,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5366\/revisions\/5370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/5368"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=5366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=5366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=5366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}