{"id":5335,"date":"2026-02-03T15:00:20","date_gmt":"2026-02-03T18:00:20","guid":{"rendered":"https:\/\/semapi.com.br\/?p=5335"},"modified":"2026-02-05T15:35:09","modified_gmt":"2026-02-05T18:35:09","slug":"mix-de-cases-usemol","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/mix-de-cases-usemol\/","title":{"rendered":"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A \u00e1rea de compras deixou de ser apenas um setor operacional. Hoje,&nbsp;<strong>decis\u00f5es de compras impactam diretamente a competitividade e os resultados da empresa<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com mais de 25 anos de atua\u00e7\u00e3o, o&nbsp;<strong>Portal de Compras&nbsp;Usemol<\/strong>&nbsp;tem ajudado empresas de diferentes setores a&nbsp;<strong>otimizar processos, reduzir custos e gerar resultados concretos<\/strong>, transformando a fun\u00e7\u00e3o de compras em um verdadeiro diferencial estrat\u00e9gico. Confira tudo isso na pr\u00e1tica!&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cases de sucesso<\/strong>\u00a0<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Transporte de&nbsp;g\u00e1s:&nbsp;redu\u00e7\u00e3o de&nbsp;lead&nbsp;time e&nbsp;amplia\u00e7\u00e3o de&nbsp;fornecedores<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em uma transportadora de g\u00e1s, o&nbsp;Usemol&nbsp;conseguiu reduzir o&nbsp;<strong>lead time de compras de 9 meses para apenas 45 dias<\/strong>, aumentando a transpar\u00eancia e expandindo a base para cerca de&nbsp;<strong>50 mil fornecedores<\/strong>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Petr\u00f3leo e&nbsp;g\u00e1s:&nbsp;economia&nbsp;milion\u00e1ria com&nbsp;processos&nbsp;padronizados<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em uma empresa de explora\u00e7\u00e3o e produ\u00e7\u00e3o de petr\u00f3leo, mais de&nbsp;<strong>1.100 usu\u00e1rios<\/strong>&nbsp;passaram a operar com&nbsp;<strong>processos padronizados<\/strong>, gerando&nbsp;<strong>economia de milh\u00f5es no primeiro ano<\/strong>&nbsp;do m\u00f3dulo de medi\u00e7\u00f5es, al\u00e9m de reduzir juros e moras.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Ind\u00fastria:&nbsp;visibilidade e&nbsp;governan\u00e7a que&nbsp;geram&nbsp;competitividade<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Grupos industriais que n\u00e3o obtiveram sucesso com outras plataformas migraram para o&nbsp;Usemol, conquistando:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dashboards e relat\u00f3rios personalizados\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Novos modelos de governan\u00e7a\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Funcionalidades que aumentaram a competitividade entre fornecedores\u00a0<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Distribui\u00e7\u00e3o de&nbsp;combust\u00edveis e&nbsp;infraestrutura:&nbsp;processos&nbsp;integrados&nbsp;e&nbsp;automatizados<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O&nbsp;Usemol&nbsp;estruturou&nbsp;processos completos de compras e medi\u00e7\u00f5es,&nbsp;<strong>eliminando controles manuais em Excel<\/strong>&nbsp;e entregando metodologias baseadas em:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cronogramas\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sub-itens\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Documenta\u00e7\u00e3o integrada\u00a0<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Varejo:&nbsp;expans\u00e3o&nbsp;r\u00e1pida com&nbsp;controle e&nbsp;compliance<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Redes de supermercados aceleraram sua expans\u00e3o adotando:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conceito de\u00a0\u201cloja padr\u00e3o\u201d\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cat\u00e1logos permanentes\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leil\u00f5es estruturados\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tudo isso mantendo&nbsp;controle financeiro&nbsp;e&nbsp;compliance.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6. Sa\u00fade:&nbsp;compras&nbsp;hospitalares&nbsp;centralizadas<\/strong>&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hospitais centralizaram suas compras em&nbsp;um \u00fanico ambiente, integrando m\u00faltiplos portais de fornecedores e elevando&nbsp;governan\u00e7a e agilidade&nbsp;em processos cr\u00edticos.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Compras como&nbsp;decis\u00e3o&nbsp;estrat\u00e9gica<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os cases apresentados mostram que, com processos bem estruturados e tecnologia adequada, a \u00e1rea de compras deixa de ser apenas operacional e passa a sustentar decis\u00f5es estrat\u00e9gicas em toda a empresa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o&nbsp;Usemol,&nbsp;empresas que lidam com&nbsp;<strong>complexidade, escala e press\u00e3o por resultados<\/strong>&nbsp;encontram uma plataforma confi\u00e1vel para transformar a opera\u00e7\u00e3o em vantagem competitiva.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>A \u00e1rea de compras deixou de ser apenas um setor operacional. Hoje,&nbsp;decis\u00f5es de compras impactam diretamente a competitividade e os resultados da empresa.&nbsp;&nbsp; Com mais de 25 anos de atua\u00e7\u00e3o, o&nbsp;Portal de Compras&nbsp;Usemol&nbsp;tem ajudado empresas de diferentes setores a&nbsp;otimizar processos, reduzir custos e gerar resultados concretos, transformando a fun\u00e7\u00e3o de compras em um verdadeiro diferencial [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":5336,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":6,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-5335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/mix-de-cases-usemol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"A \u00e1rea de compras deixou de ser apenas um setor operacional. Hoje,&nbsp;decis\u00f5es de compras impactam diretamente a competitividade e os resultados da empresa.&nbsp;&nbsp; Com mais de 25 anos de atua\u00e7\u00e3o, o&nbsp;Portal de Compras&nbsp;Usemol&nbsp;tem ajudado empresas de diferentes setores a&nbsp;otimizar processos, reduzir custos e gerar resultados concretos, transformando a fun\u00e7\u00e3o de compras em um verdadeiro diferencial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/mix-de-cases-usemol\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T18:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T18:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar\",\"datePublished\":\"2026-02-03T18:00:20+00:00\",\"dateModified\":\"2026-02-05T18:35:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/\"},\"wordCount\":472,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mix-de-cases-do-usemol.png\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/\",\"name\":\"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mix-de-cases-do-usemol.png\",\"datePublished\":\"2026-02-03T18:00:20+00:00\",\"dateModified\":\"2026-02-05T18:35:09+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/mix-de-cases-usemol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mix-de-cases-do-usemol.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mix-de-cases-do-usemol.png\",\"width\":1024,\"height\":576,\"caption\":\"mix de cases do usemol\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/mix-de-cases-usemol\/","og_locale":"es_ES","og_type":"article","og_title":"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI","og_description":"A \u00e1rea de compras deixou de ser apenas um setor operacional. Hoje,&nbsp;decis\u00f5es de compras impactam diretamente a competitividade e os resultados da empresa.&nbsp;&nbsp; Com mais de 25 anos de atua\u00e7\u00e3o, o&nbsp;Portal de Compras&nbsp;Usemol&nbsp;tem ajudado empresas de diferentes setores a&nbsp;otimizar processos, reduzir custos e gerar resultados concretos, transformando a fun\u00e7\u00e3o de compras em um verdadeiro diferencial [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/mix-de-cases-usemol\/","og_site_name":"SEMAPI","article_published_time":"2026-02-03T18:00:20+00:00","article_modified_time":"2026-02-05T18:35:09+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","type":"image\/png"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar","datePublished":"2026-02-03T18:00:20+00:00","dateModified":"2026-02-05T18:35:09+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/"},"wordCount":472,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/","url":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/","name":"Transforma\u00e7\u00e3o da \u00e1rea de compras: 6 cases de sucesso para se inspirar - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","datePublished":"2026-02-03T18:00:20+00:00","dateModified":"2026-02-05T18:35:09+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/mix-de-cases-usemol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/mix-de-cases-usemol\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/mix-de-cases-do-usemol.png","width":1024,"height":576,"caption":"mix de cases do usemol"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=5335"}],"version-history":[{"count":1,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5335\/revisions"}],"predecessor-version":[{"id":5337,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/5335\/revisions\/5337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/5336"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=5335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=5335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=5335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}