{"id":3955,"date":"2025-06-24T15:00:13","date_gmt":"2025-06-24T18:00:13","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3955"},"modified":"2025-06-24T15:01:35","modified_gmt":"2025-06-24T18:01:35","slug":"nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/","title":{"rendered":"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio"},"content":{"rendered":"<p><span data-contrast=\"auto\">Em 14 de junho de 2017, um inc\u00eandio devastador atingiu a Torre Grenfell, um edif\u00edcio de habita\u00e7\u00e3o social com 23 andares localizado em uma das \u00e1reas mais abastadas de Londres. A trag\u00e9dia<strong> resultou na morte de 72 pessoas<\/strong> e se tornou o inc\u00eandio residencial mais letal na Gr\u00e3-Bretanha desde a Segunda Guerra Mundial.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mesmo ap\u00f3s oito anos, o impacto do desastre ainda \u00e9 profundamente sentido por familiares, sobreviventes e pela comunidade local. A torre, embora ainda de p\u00e9, permanece coberta por um envolt\u00f3rio protetor. Ap\u00f3s anos de debates e incertezas, foi anunciada a decis\u00e3o de que <strong>o edif\u00edcio ser\u00e1 finalmente demolido.<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<h1>Cr\u00edticas<\/h1>\n<p><span data-contrast=\"auto\">A decis\u00e3o foi comunicada pela vice-primeira-ministra brit\u00e2nica, Angela Rayner, durante uma reuni\u00e3o com familiares das v\u00edtimas e sobreviventes. A medida, no entanto, gerou rea\u00e7\u00f5es fortes. Representantes do grupo Grenfell Next of Kin (GNK), que atua em nome de parentes de quase metade das v\u00edtimas, lamentaram a falta de escuta durante o processo. &#8220;Gostar\u00edamos que a torre inteira pudesse ficar de p\u00e9 para sempre? Sim. Isso \u00e9 uma op\u00e7\u00e3o? N\u00e3o do ponto de vista estrutural&#8221;, afirmou o grupo, <strong>ressaltando os riscos apontados por engenheiros<\/strong> que acompanham a condi\u00e7\u00e3o do edif\u00edcio.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Outra entidade, a Grenfell United, criticou duramente o que classificou como uma consulta superficial, realizada em apenas quatro semanas, <strong>e condenou a exclus\u00e3o das fam\u00edlias das decis\u00f5es<\/strong> que envolvem o &#8220;t\u00famulo de seus entes queridos&#8221;.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Parlamentares locais, como Joe Powell, afirmaram que a decis\u00e3o foi tomada com seriedade, reconhecendo a carga simb\u00f3lica da torre. A expectativa \u00e9 de que o desmonte seja conduzido com o m\u00e1ximo de cuidado e respeito, conforme orienta\u00e7\u00f5es de uma comiss\u00e3o respons\u00e1vel pela elabora\u00e7\u00e3o de um memorial futuro.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1>Respostas<\/h1>\n<p><span data-contrast=\"auto\">O inqu\u00e9rito p\u00fablico sobre a trag\u00e9dia, finalizado no ano passado, atribuiu a responsabilidade do <a href=\"https:\/\/semapi.com.br\/es\/dia-da-industria-a-importancia-da-seguranca-contra-incendios-e-o-papel-das-normas-nfpa\/\">inc\u00eandio<\/a> a uma s\u00e9rie <strong>de falhas governamentais, regulat\u00f3rias<\/strong> e, sobretudo, ao uso de revestimentos inflam\u00e1veis por empresas envolvidas na reforma da torre. Muitos sobreviventes e familiares ainda aguardam desdobramentos legais, e criticam a lentid\u00e3o na responsabiliza\u00e7\u00e3o criminal.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A proposta de memorial definitivo est\u00e1 prevista para ser apresentada em 2026, com obras que podem come\u00e7ar ainda naquele ano. <\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em 2018, <a href=\"https:\/\/semapi.com.br\/es\/nfpa-confira-5-motivos-para-seguir-as-normas-de-sistemas-de-combate-a-incendio\/\">a NFPA<\/a> lan\u00e7ou o NFPA Fire &amp; Life Safety Ecosystem, um modelo desenvolvido <strong>como resposta ao inc\u00eandio da Torre Grenfell<\/strong> e a outros eventos que evidenciaram falhas graves nos sistemas de seguran\u00e7a. O ecossistema prop\u00f5e uma estrutura composta por oito elementos interdependentes, todos essenciais para garantir um ambiente seguro. A falha em qualquer um desses componentes <strong>pode comprometer todo o sistema<\/strong>, resultando em mortes, feridos e perdas materiais, explica o <a href=\"https:\/\/www.nfpa.org\/news-blogs-and-articles\/nfpa-journal\/2024\/11\/15\/lessons-from-grenfell\">site da NFPA. <\/a><\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">No caso de Grenfell, o relat\u00f3rio final da investiga\u00e7\u00e3o p\u00fablica representa <a href=\"https:\/\/semapi.com.br\/es\/nfpa-qual-a-diferenca-entre-as-normas-nfpa-20-e-nfpa-25\/\">um retrato detalhado do colapso<\/a> total desse ecossistema de seguran\u00e7a, com defici\u00eancias cr\u00edticas em \u00e1reas como responsabilidade governamental, conformidade com c\u00f3digos, ado\u00e7\u00e3o de normas t\u00e9cnicas, qualifica\u00e7\u00e3o da for\u00e7a de trabalho, investimentos em seguran\u00e7a e preparo para emerg\u00eancias. Esses pontos fragilizados ajudaram a criar as condi\u00e7\u00f5es para que a trag\u00e9dia ocorresse.<\/span><\/p>\n<p><span data-contrast=\"auto\">Na Semapi, o compromisso com a seguran\u00e7a <a href=\"https:\/\/semapi.com.br\/es\/bhopal-1984-o-acidente-industrial-que-expos-a-cidade-indiana-a-um-gas-toxico\/\">vai al\u00e9m da preven\u00e7\u00e3o<\/a>. \u00c9 uma responsabilidade cont\u00ednua guiada pelas normas e boas pr\u00e1ticas internacionais, <strong>como as estabelecidas pela NFPA<\/strong>. Atuando com rigor t\u00e9cnico em inspe\u00e7\u00f5es, testes e manuten\u00e7\u00e3o de sistemas de combate a inc\u00eandio, a Semapi contribui ativamente para a <strong>constru\u00e7\u00e3o de um ambiente mais seguro.<\/strong> <a href=\"https:\/\/semapi.com.br\/es\/fale-conosco\/\">Entre em contato<\/a> com a Semapi e saiba como garantir conformidade com as normas NFPA.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>*Com informa\u00e7\u00f5es da CNN Brasil e NFPA.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em 14 de junho de 2017, um inc\u00eandio devastador atingiu a Torre Grenfell, um edif\u00edcio de habita\u00e7\u00e3o social com 23 andares localizado em uma das \u00e1reas mais abastadas de Londres. A trag\u00e9dia resultou na morte de 72 pessoas e se tornou o inc\u00eandio residencial mais letal na Gr\u00e3-Bretanha desde a Segunda Guerra Mundial.\u00a0 Mesmo ap\u00f3s [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3961,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":28,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Em 14 de junho de 2017, um inc\u00eandio devastador atingiu a Torre Grenfell, um edif\u00edcio de habita\u00e7\u00e3o social com 23 andares localizado em uma das \u00e1reas mais abastadas de Londres. A trag\u00e9dia resultou na morte de 72 pessoas e se tornou o inc\u00eandio residencial mais letal na Gr\u00e3-Bretanha desde a Segunda Guerra Mundial.\u00a0 Mesmo ap\u00f3s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T18:00:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T18:01:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio\",\"datePublished\":\"2025-06-24T18:00:13+00:00\",\"dateModified\":\"2025-06-24T18:01:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fire4.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/\",\"name\":\"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fire4.jpg\",\"datePublished\":\"2025-06-24T18:00:13+00:00\",\"dateModified\":\"2025-06-24T18:01:35+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fire4.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fire4.jpg\",\"width\":1024,\"height\":535,\"caption\":\"fire\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/","og_locale":"es_ES","og_type":"article","og_title":"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI","og_description":"Em 14 de junho de 2017, um inc\u00eandio devastador atingiu a Torre Grenfell, um edif\u00edcio de habita\u00e7\u00e3o social com 23 andares localizado em uma das \u00e1reas mais abastadas de Londres. A trag\u00e9dia resultou na morte de 72 pessoas e se tornou o inc\u00eandio residencial mais letal na Gr\u00e3-Bretanha desde a Segunda Guerra Mundial.\u00a0 Mesmo ap\u00f3s [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/","og_site_name":"SEMAPI","article_published_time":"2025-06-24T18:00:13+00:00","article_modified_time":"2025-06-24T18:01:35+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio","datePublished":"2025-06-24T18:00:13+00:00","dateModified":"2025-06-24T18:01:35+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/"},"wordCount":637,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/","url":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/","name":"NFPA e o desastre da torre Grenfell: li\u00e7\u00f5es para a seguran\u00e7a contra inc\u00eandio - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","datePublished":"2025-06-24T18:00:13+00:00","dateModified":"2025-06-24T18:01:35+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/en\/nfpa-e-o-desastre-da-torre-grenfell-licoes-para-a-seguranca-contra-incendio\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/fire4.jpg","width":1024,"height":535,"caption":"fire"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3955"}],"version-history":[{"count":7,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3955\/revisions"}],"predecessor-version":[{"id":3963,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3955\/revisions\/3963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3961"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}