{"id":3949,"date":"2025-06-24T09:24:52","date_gmt":"2025-06-24T12:24:52","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3949"},"modified":"2025-06-24T09:24:52","modified_gmt":"2025-06-24T12:24:52","slug":"o-que-e-ferrografia-entenda-a-importancia-da-tecnica","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/","title":{"rendered":"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica"},"content":{"rendered":"<p><span data-contrast=\"auto\">No universo da manuten\u00e7\u00e3o preditiva, a ferrografia se destaca como uma t\u00e9cnica poderosa e precisa para o monitoramento da sa\u00fade de m\u00e1quinas e equipamentos. Baseada em princ\u00edpios tribol\u00f3gicos \u2014 a ci\u00eancia que estuda a intera\u00e7\u00e3o entre superf\u00edcies em movimento \u2014, essa metodologia permite identificar e classificar part\u00edculas presentes em \u00f3leos lubrificantes, fornecendo diagn\u00f3sticos antecipados sobre o estado dos componentes mec\u00e2nicos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A ferrografia \u00e9 uma t\u00e9cnica laboratorial voltada \u00e0 an\u00e1lise de part\u00edculas met\u00e1licas e n\u00e3o met\u00e1licas presentes em amostras de lubrificantes. Por meio da observa\u00e7\u00e3o da morfologia, colora\u00e7\u00e3o, tamanho e natureza dessas part\u00edculas \u2014 como limalhas met\u00e1licas, areia, borra, fuligem e fibras org\u00e2nicas \u2014, \u00e9 poss\u00edvel entender <a href=\"https:\/\/semapi.com.br\/es\/deteccao-de-gases-o-que-e-e-como-funciona\/\">o tipo de desgaste<\/a> que ocorre nos componentes internos das m\u00e1quinas, identificar contaminantes e at\u00e9 avaliar o desempenho do pr\u00f3prio lubrificante.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O principal objetivo da ferrografia \u00e9 diagnosticar a severidade do desgaste, possibilitando a tomada de decis\u00f5es estrat\u00e9gicas sobre manuten\u00e7\u00e3o, evitando falhas inesperadas, otimizando a performance dos ativos e estendendo sua vida \u00fatil.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">Diferentes tipos!<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A ferrografia se divide em dois tipos principais de <a href=\"https:\/\/semapi.com.br\/es\/o-que-e-lubrificacao-industrial\/\">an\u00e1lise<\/a>: anal\u00edtica e quantitativa.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Exame anal\u00edtico:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"> Essa modalidade se concentra na visualiza\u00e7\u00e3o direta das part\u00edculas sob o microsc\u00f3pio. A an\u00e1lise permite diagnosticar o tipo de desgaste (como abras\u00e3o, esfolia\u00e7\u00e3o ou corros\u00e3o), sua origem e severidade. As part\u00edculas podem ser classificadas pela forma (laminares, esf\u00e9ricas) ou natureza (pol\u00edmeros, \u00f3xidos, contaminantes org\u00e2nicos).<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Exame quantitativo (leitura direta):<\/span><\/p>\n<p><span data-contrast=\"auto\"> Aqui, o foco est\u00e1 na medi\u00e7\u00e3o do tamanho e da quantidade de part\u00edculas. Utilizando o ferrosc\u00f3pio, as part\u00edculas s\u00e3o classificadas em duas categorias: Large (L) para part\u00edculas maiores que 5 \u00b5m, e Small (S) para aquelas iguais ou menores que 5 \u00b5m. A an\u00e1lise quantitativa \u00e9 usada para identificar tend\u00eancias de desgaste ao longo do tempo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">Onde aplicar<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A versatilidade da ferrografia permite sua <a href=\"https:\/\/semapi.com.br\/es\/ultrassom-na-manutencao-preditiva-o-que-e-como-funciona-e-por-que-e-essencial\/\">aplica\u00e7\u00e3o<\/a> em diversos setores da ind\u00fastria. Equipamentos como redutores, turbo-geradores, motores a diesel, sistemas hidr\u00e1ulicos, mancais, compressores centr\u00edfugos, de parafuso ou alternativos, s\u00e3o exemplos de ativos que se beneficiam diretamente dessa t\u00e9cnica.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ao permitir um diagn\u00f3stico preciso e antecipado de falhas, a ferrografia contribui para:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Aumento da confiabilidade operacional;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Redu\u00e7\u00e3o de custos com manuten\u00e7\u00f5es corretivas;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Planejamento mais eficiente das paradas t\u00e9cnicas;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Maior vida \u00fatil de componentes e lubrificantes.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Com expertise em an\u00e1lises preditivas e diagn\u00f3stico de falhas, a Semapi utiliza a ferrografia para antecipar problemas, otimizar recursos e garantir a m\u00e1xima confiabilidade dos ativos dos nossos clientes. <a href=\"https:\/\/semapi.com.br\/es\/fale-conosco\/\">Entre em contato<\/a> com nossos especialistas e descubra como essa solu\u00e7\u00e3o pode transformar a gest\u00e3o da manuten\u00e7\u00e3o na sua empresa.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>No universo da manuten\u00e7\u00e3o preditiva, a ferrografia se destaca como uma t\u00e9cnica poderosa e precisa para o monitoramento da sa\u00fade de m\u00e1quinas e equipamentos. Baseada em princ\u00edpios tribol\u00f3gicos \u2014 a ci\u00eancia que estuda a intera\u00e7\u00e3o entre superf\u00edcies em movimento \u2014, essa metodologia permite identificar e classificar part\u00edculas presentes em \u00f3leos lubrificantes, fornecendo diagn\u00f3sticos antecipados sobre [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3953,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":132,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"No universo da manuten\u00e7\u00e3o preditiva, a ferrografia se destaca como uma t\u00e9cnica poderosa e precisa para o monitoramento da sa\u00fade de m\u00e1quinas e equipamentos. Baseada em princ\u00edpios tribol\u00f3gicos \u2014 a ci\u00eancia que estuda a intera\u00e7\u00e3o entre superf\u00edcies em movimento \u2014, essa metodologia permite identificar e classificar part\u00edculas presentes em \u00f3leos lubrificantes, fornecendo diagn\u00f3sticos antecipados sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T12:24:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica\",\"datePublished\":\"2025-06-24T12:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/quimic2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/\",\"name\":\"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/quimic2.jpg\",\"datePublished\":\"2025-06-24T12:24:52+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/quimic2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/quimic2.jpg\",\"width\":1200,\"height\":627,\"caption\":\"quimic\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/","og_locale":"es_ES","og_type":"article","og_title":"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI","og_description":"No universo da manuten\u00e7\u00e3o preditiva, a ferrografia se destaca como uma t\u00e9cnica poderosa e precisa para o monitoramento da sa\u00fade de m\u00e1quinas e equipamentos. Baseada em princ\u00edpios tribol\u00f3gicos \u2014 a ci\u00eancia que estuda a intera\u00e7\u00e3o entre superf\u00edcies em movimento \u2014, essa metodologia permite identificar e classificar part\u00edculas presentes em \u00f3leos lubrificantes, fornecendo diagn\u00f3sticos antecipados sobre [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/","og_site_name":"SEMAPI","article_published_time":"2025-06-24T12:24:52+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica","datePublished":"2025-06-24T12:24:52+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/"},"wordCount":471,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/","url":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/","name":"O que \u00e9 ferrografia? Entenda a import\u00e2ncia da t\u00e9cnica - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","datePublished":"2025-06-24T12:24:52+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/o-que-e-ferrografia-entenda-a-importancia-da-tecnica\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/quimic2.jpg","width":1200,"height":627,"caption":"quimic"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3949"}],"version-history":[{"count":4,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3949\/revisions"}],"predecessor-version":[{"id":3954,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3949\/revisions\/3954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3953"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}