{"id":3936,"date":"2025-06-18T08:52:03","date_gmt":"2025-06-18T11:52:03","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3936"},"modified":"2025-06-18T08:52:03","modified_gmt":"2025-06-18T11:52:03","slug":"o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/","title":{"rendered":"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente"},"content":{"rendered":"<p><span data-contrast=\"auto\">A gest\u00e3o de contratos \u00e9 uma \u00e1rea cr\u00edtica para o sucesso operacional e financeiro das empresas. Quando negligenciada ou feita de forma manual, <strong>abre espa\u00e7o para falhas<\/strong> que comprometem custos, prazos, qualidade e compliance.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Sem uma <a href=\"https:\/\/semapi.com.br\/es\/controle-de-custos-e-gestao-de-riscos-5-motivos-para-utilizar-utilizar-o-usemol-na-gestao-de-contratos\/\">metodologia estruturada de medi\u00e7\u00e3o de contratos<\/a> e acompanhamento de SLAs (Acordos de N\u00edvel de Servi\u00e7o), as empresas enfrentam desafios como:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li><span data-contrast=\"auto\"><strong>Baixa qualidade de servi\u00e7os:<\/strong> a falta de monitoramento dos contratos impede o controle sobre entregas e prazos, resultando em servi\u00e7os mal executados e insatisfa\u00e7\u00e3o;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Custos elevados:<\/strong> sem visibilidade e controle, ocorrem desperd\u00edcios, pagamentos indevidos e perda de oportunidades de economia;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Atrasos nos pagamentos:<\/strong> a desorganiza\u00e7\u00e3o dos processos contratuais afeta a libera\u00e7\u00e3o de pagamentos, impactando diretamente o relacionamento com fornecedores;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Riscos de n\u00e3o conformidade:<\/strong> sem ferramentas adequadas, aumentam as chances de descumprimento de cl\u00e1usulas, normas regulat\u00f3rias e pol\u00edticas internas \u2014 o que pode levar a san\u00e7\u00f5es e preju\u00edzos reputacionais;<\/span><\/li>\n<\/ul>\n<h1>Sem obst\u00e1culos!<\/h1>\n<p><span data-contrast=\"auto\">O m\u00f3dulo de medi\u00e7\u00e3o de contratos do <a href=\"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/\">portal de compras Usemol<\/a> foi desenvolvido para enfrentar todos esses desafios de forma inteligente, automatizada e estrat\u00e9gica.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Com ele, sua empresa tem acesso a:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li><span data-contrast=\"auto\"><strong>Transpar\u00eancia e conformidade:<\/strong> clareza nos termos contratuais, minimizando lit\u00edgios e riscos regulat\u00f3rios;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Controle de custos:<\/strong> pagamento apenas por entregas comprovadas, com economia e rigor or\u00e7ament\u00e1rio;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Gest\u00e3o de desempenho:<\/strong> avalia\u00e7\u00e3o cont\u00ednua da performance dos fornecedores com base em indicadores e SLAs;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Efici\u00eancia operacional:<\/strong> processos padronizados e automatizados, com economia de tempo e recursos;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Tomada de decis\u00e3o estrat\u00e9gica:<\/strong> KPIs e relat\u00f3rios para decis\u00f5es mais assertivas sobre fornecedores e contratos;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Gest\u00e3o de riscos:<\/strong> monitoramento constante que reduz vulnerabilidades relacionadas \u00e0 qualidade e conformidade;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Relacionamento fortalecido com fornecedores:<\/strong> processos transparentes e justos que constroem parcerias de longo prazo;<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong> Integra\u00e7\u00e3o com ERP:<\/strong> sincroniza\u00e7\u00e3o direta com os sistemas da empresa, garantindo agilidade e precis\u00e3o em pagamentos e aprova\u00e7\u00f5es;<\/span><\/li>\n<\/ul>\n<h1><span data-contrast=\"auto\">Avalia\u00e7\u00e3o dos SLAs dos fornecedores <\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">Com <a href=\"https:\/\/semapi.com.br\/es\/usemol-inteligencia-artificial-transforma-sua-gestao-de-suprimentos-em-resultados\/\">o Usemol,<\/a> sua empresa pode monitorar de forma cont\u00ednua os Acordos de N\u00edvel de Servi\u00e7o, garantindo a entrega de servi\u00e7os conforme o esperado<strong> e mantendo a efici\u00eancia operacional.<\/strong> Tudo isso com indicadores precisos, integra\u00e7\u00e3o e vis\u00e3o completa da evolu\u00e7\u00e3o f\u00edsica e financeira de cada projeto. <\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mais do que controlar verbas, prazos e entregas, o m\u00f3dulo de gest\u00e3o de contratos do Portal USEMOL ajuda sua empresa a garantir economia, mitigar riscos e otimizar processos de ponta a ponta.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\"><a href=\"https:\/\/semapi.com.br\/es\/fale-conosco\/\">Fale com o nosso time<\/a> e veja como a sua gest\u00e3o de contratos pode dar um salto de efici\u00eancia.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o de contratos \u00e9 uma \u00e1rea cr\u00edtica para o sucesso operacional e financeiro das empresas. Quando negligenciada ou feita de forma manual, abre espa\u00e7o para falhas que comprometem custos, prazos, qualidade e compliance.\u00a0 Sem uma metodologia estruturada de medi\u00e7\u00e3o de contratos e acompanhamento de SLAs (Acordos de N\u00edvel de Servi\u00e7o), as empresas enfrentam desafios [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":7,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"A gest\u00e3o de contratos \u00e9 uma \u00e1rea cr\u00edtica para o sucesso operacional e financeiro das empresas. Quando negligenciada ou feita de forma manual, abre espa\u00e7o para falhas que comprometem custos, prazos, qualidade e compliance.\u00a0 Sem uma metodologia estruturada de medi\u00e7\u00e3o de contratos e acompanhamento de SLAs (Acordos de N\u00edvel de Servi\u00e7o), as empresas enfrentam desafios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T11:52:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente\",\"datePublished\":\"2025-06-18T11:52:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/contrato2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/\",\"name\":\"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/contrato2.jpg\",\"datePublished\":\"2025-06-18T11:52:03+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/contrato2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/contrato2.jpg\",\"width\":1024,\"height\":535,\"caption\":\"contrato\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/","og_locale":"es_ES","og_type":"article","og_title":"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI","og_description":"A gest\u00e3o de contratos \u00e9 uma \u00e1rea cr\u00edtica para o sucesso operacional e financeiro das empresas. Quando negligenciada ou feita de forma manual, abre espa\u00e7o para falhas que comprometem custos, prazos, qualidade e compliance.\u00a0 Sem uma metodologia estruturada de medi\u00e7\u00e3o de contratos e acompanhamento de SLAs (Acordos de N\u00edvel de Servi\u00e7o), as empresas enfrentam desafios [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/","og_site_name":"SEMAPI","article_published_time":"2025-06-18T11:52:03+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente","datePublished":"2025-06-18T11:52:03+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/"},"wordCount":455,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/","url":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/","name":"O que pode dar errado quando sua empresa n\u00e3o mede contratos corretamente - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","datePublished":"2025-06-18T11:52:03+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/o-que-pode-dar-errado-quando-sua-empresa-nao-mede-contratos-corretamente\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/contrato2.jpg","width":1024,"height":535,"caption":"contrato"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3936"}],"version-history":[{"count":7,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3936\/revisions"}],"predecessor-version":[{"id":3943,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3936\/revisions\/3943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3944"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}