{"id":3923,"date":"2025-06-16T09:39:51","date_gmt":"2025-06-16T12:39:51","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3923"},"modified":"2025-06-16T09:39:51","modified_gmt":"2025-06-16T12:39:51","slug":"leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/","title":{"rendered":"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol"},"content":{"rendered":"<p><span data-contrast=\"auto\">Sua empresa tem um estoque parado de itens que n\u00e3o ser\u00e3o mais utilizados? Empresas que lidam com estoques excedentes ou <a href=\"https:\/\/semapi.com.br\/es\/manutencao-preditiva-evita-prejuizo-de-5-dias-em-fabrica-de-papel\/\">equipamentos<\/a> fora de uso conhecem bem<strong> os impactos negativos<\/strong> que esses itens causam: ocupa\u00e7\u00e3o de espa\u00e7o, custos desnecess\u00e1rios e dinheiro parado.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em vez de deix\u00e1-los ocupando espa\u00e7o e gerando custo, voc\u00ea pode anunci\u00e1-los atrav\u00e9s do <a href=\"https:\/\/semapi.com.br\/es\/controle-de-custos-e-gestao-de-riscos-5-motivos-para-utilizar-utilizar-o-usemol-na-gestao-de-contratos\/\">portal de compras Usemol<\/a> e <strong>atrair compradores que realmente precisam desses materiais<\/strong> \u2014 criando uma receita atrav\u00e9s da desmobiliza\u00e7\u00e3o de ativos.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para isso, o portal Usemol atua lado a lado com a Bom Valor, empresa <strong>especializada em desmobiliza\u00e7\u00e3o de ativos,<\/strong> que aplica a <a href=\"https:\/\/semapi.com.br\/es\/compras-inteligentes-como-a-ia-pode-evitar-rupturas-e-excesso-de-estoque-nas-farmacias\/\">tecnologia<\/a> blockchain para garantir autenticidade, rastreabilidade e seguran\u00e7a nas transa\u00e7\u00f5es envolvendo ativos obsoletos ou sucatas. \u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A Bom Valor <a href=\"https:\/\/mercado.bomvalor.com.br\/\">possui uma plataforma descentralizada<\/a> que permite a participa\u00e7\u00e3o de m\u00faltiplos leiloeiros homologados, ampliando a visibilidade dos ativos e aumentando a competitividade entre compradores. Garantindo que seus ativos obsoletos (como m\u00e1quinas, equipamentos industriais ou sucatas) sejam comercializados de forma transparente e eficiente, maximizando seus resultados.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">O que \u00e9 o leil\u00e3o de obsoletos?\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">Trata-se de uma funcionalidade pensada <strong>para transformar materiais inativos em receita<\/strong>, por meio de um processo de leil\u00e3o organizado, transparente e com alta visibilidade. \u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al\u00e9m de contribuir com o fluxo financeiro e a gest\u00e3o de estoque, a desmobiliza\u00e7\u00e3o de ativos tamb\u00e9m promove a sustentabilidade, ao incentivar o reaproveitamento e evitar o descarte prematuro.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Como funciona?\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ol>\n<li><span data-contrast=\"auto\"> Cadastro do lote<\/span><\/li>\n<\/ol>\n<p><span data-contrast=\"auto\">A empresa vendedora insere os itens na plataforma com todas as informa\u00e7\u00f5es relevantes: especifica\u00e7\u00f5es t\u00e9cnicas, quantidades, estado de conserva\u00e7\u00e3o e outros dados \u00fateis.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ol start=\"2\">\n<li><span data-contrast=\"auto\"> Visibilidade ampliada<\/span><\/li>\n<\/ol>\n<p><span data-contrast=\"auto\">Os lotes cadastrados s\u00e3o divulgados para uma base de compradores interessados, garantindo ampla exposi\u00e7\u00e3o e maior chance de negocia\u00e7\u00e3o.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ol start=\"3\">\n<li><span data-contrast=\"auto\"> Din\u00e2mica do leil\u00e3o\u00a0<\/span><\/li>\n<\/ol>\n<p><span data-contrast=\"auto\">Os compradores realizam lances em tempo real, promovendo um ambiente competitivo e transparente, ideal para maximizar o valor de venda.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ol start=\"4\">\n<li><span data-contrast=\"auto\"> Fechamento e conclus\u00e3o\u00a0<\/span><\/li>\n<\/ol>\n<p><span data-contrast=\"auto\">Ao final do leil\u00e3o, o leiloeiro faz a intermedia\u00e7\u00e3o da venda, comunica o resultado \u00e0 empresa vendedora e conclui a opera\u00e7\u00e3o com presta\u00e7\u00e3o de contas completa.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">Quais s\u00e3o as vantagens?\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">Para quem vende:\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Libera\u00e7\u00e3o de espa\u00e7o f\u00edsico e redu\u00e7\u00e3o de custos com armazenagem;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Gera\u00e7\u00e3o de receita com ativos que estavam parados;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Processo \u00e1gil e seguro, com pouca burocracia;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para quem compra:\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Acesso a produtos com pre\u00e7os competitivos;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Variedade de itens para diferentes demandas;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Seguran\u00e7a e transpar\u00eancia durante todo o processo;\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al\u00e9m da efici\u00eancia operacional, o Leil\u00e3o de Obsoletos \u00e9 uma iniciativa alinhada com a responsabilidade socioambiental, cada vez mais valorizada no mercado. Empresas que reutilizam recursos de forma inteligente se destacam pela inova\u00e7\u00e3o e comprometimento com a sustentabilidade.\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">N\u00e3o deixe seus ativos parados perderem valor. <a href=\"https:\/\/semapi.com.br\/es\/fale-conosco\/\">Entre em contato<\/a> e transforme seu estoque excedente em receita.\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Sua empresa tem um estoque parado de itens que n\u00e3o ser\u00e3o mais utilizados? Empresas que lidam com estoques excedentes ou equipamentos fora de uso conhecem bem os impactos negativos que esses itens causam: ocupa\u00e7\u00e3o de espa\u00e7o, custos desnecess\u00e1rios e dinheiro parado.\u00a0\u00a0 Em vez de deix\u00e1-los ocupando espa\u00e7o e gerando custo, voc\u00ea pode anunci\u00e1-los atrav\u00e9s do [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":199,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Sua empresa tem um estoque parado de itens que n\u00e3o ser\u00e3o mais utilizados? Empresas que lidam com estoques excedentes ou equipamentos fora de uso conhecem bem os impactos negativos que esses itens causam: ocupa\u00e7\u00e3o de espa\u00e7o, custos desnecess\u00e1rios e dinheiro parado.\u00a0\u00a0 Em vez de deix\u00e1-los ocupando espa\u00e7o e gerando custo, voc\u00ea pode anunci\u00e1-los atrav\u00e9s do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-16T12:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol\",\"datePublished\":\"2025-06-16T12:39:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/estoque2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/\",\"name\":\"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/estoque2.jpg\",\"datePublished\":\"2025-06-16T12:39:51+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/estoque2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/estoque2.jpg\",\"width\":1024,\"height\":535,\"caption\":\"estoque\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/","og_locale":"es_ES","og_type":"article","og_title":"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI","og_description":"Sua empresa tem um estoque parado de itens que n\u00e3o ser\u00e3o mais utilizados? Empresas que lidam com estoques excedentes ou equipamentos fora de uso conhecem bem os impactos negativos que esses itens causam: ocupa\u00e7\u00e3o de espa\u00e7o, custos desnecess\u00e1rios e dinheiro parado.\u00a0\u00a0 Em vez de deix\u00e1-los ocupando espa\u00e7o e gerando custo, voc\u00ea pode anunci\u00e1-los atrav\u00e9s do [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/","og_site_name":"SEMAPI","article_published_time":"2025-06-16T12:39:51+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol","datePublished":"2025-06-16T12:39:51+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/"},"wordCount":490,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/","url":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/","name":"Leil\u00e3o de obsoletos: transforme seu estoque parado em receita com o Usemol - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","datePublished":"2025-06-16T12:39:51+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/leilao-de-obsoletos-transforme-seu-estoque-parado-em-receita-com-o-usemol\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/06\/estoque2.jpg","width":1024,"height":535,"caption":"estoque"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3923"}],"version-history":[{"count":3,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3923\/revisions"}],"predecessor-version":[{"id":3926,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3923\/revisions\/3926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3927"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}