{"id":3477,"date":"2025-04-25T10:57:01","date_gmt":"2025-04-25T13:57:01","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3477"},"modified":"2025-04-25T10:57:48","modified_gmt":"2025-04-25T13:57:48","slug":"abril-verde-conheca-a-historia-por-tras-da-campanha","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/abril-verde-conheca-a-historia-por-tras-da-campanha\/","title":{"rendered":"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha"},"content":{"rendered":"<p><span data-contrast=\"auto\">O Abril Verde vai muito al\u00e9m de uma cor no calend\u00e1rio. Simboliza uma causa urgente e essencial: <strong>a prote\u00e7\u00e3o da vida dos trabalhadores.\u00a0<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">Para criar a\u00e7\u00f5es eficazes em seguran\u00e7a do trabalho, \u00e9 fundamental compreender n\u00e3o apenas o objetivo da campanha, mas tamb\u00e9m sua origem e o que ela representa.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1>A trag\u00e9dia<\/h1>\n<p><span data-contrast=\"auto\">Em novembro de 1968, uma explos\u00e3o devastadora atingiu uma mina de carv\u00e3o na cidade de Farmington, no estado da Virg\u00ednia, nos Estados Unidos.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O incidente (destacado na foto acima), conhecido como o Desastre da Mina de Farmington, tirou a vida de 78 trabalhadores, conforme contextualizado pelo blog do Sesi.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O inc\u00eandio gerado pela explos\u00e3o foi t\u00e3o intenso que os acessos \u00e0 mina precisaram ser selados para conter o fogo \u2014 e os <strong>corpos de 19 v\u00edtimas nunca foram encontrados.\u00a0<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">Essa trag\u00e9dia foi um marco que escancarou a necessidade urgente de fortalecer as normas de seguran\u00e7a e proteger quem coloca sua vida em risco diariamente.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><b><span data-contrast=\"auto\">Reconhecimento internacional<\/span><\/b><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">\u201cMantendo a lembran\u00e7a do acidente, mas passando o foco para a preven\u00e7\u00e3o, a Organiza\u00e7\u00e3o Internacional do Trabalho (OIT) instituiu a data, em 2003, tamb\u00e9m como o Dia Mundial de Seguran\u00e7a e Sa\u00fade no Trabalho\u201d, explica a Ag\u00eancia Senado.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">No Brasil, o Abril Verde surgiu como um movimento para dar visibilidade \u00e0 import\u00e2ncia da preven\u00e7\u00e3o de acidentes e doen\u00e7as ocupacionais.\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Desde ent\u00e3o,<a href=\"https:\/\/semapi.com.br\/es\/monitoramento-e-manutencao-preditiva-reducao-de-paradas-e-otimizacao-de-producao\/\"> o m\u00eas de abril se tornou refer\u00eancia<\/a> para <strong>campanhas, a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e iniciativas<\/strong> voltadas \u00e0 seguran\u00e7a no ambiente corporativo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>A Semapi, com mais de uma d\u00e9cada de experi\u00eancia<a href=\"https:\/\/semapi.com.br\/es\/quem-somos\/\"> em manuten\u00e7\u00e3o preditiva<\/a>, refor\u00e7a seu compromisso com a seguran\u00e7a e a sa\u00fade no ambiente de trabalho durante o Abril Verde.<\/p>\n<p><span data-teams=\"true\">&#8220;Todo ano, milhares de pessoas sofrem acidentes ou adoecem no trabalho. A maioria desses casos poderia ser evitada com preven\u00e7\u00e3o, aten\u00e7\u00e3o e o uso correto dos equipamentos. O Abril Verde \u00e9 um lembrete: nossa vida e a dos nossos colegas valem mais do que qualquer pressa. Seguran\u00e7a \u00e9 prioridade na Semapi&#8221;, <a href=\"https:\/\/semapi.com.br\/es\/usemol-participa-da-21a-maratona-de-supply-chain-e-reforca-papel-estrategico-das-compras-nas-empresas\/\">explica<\/a> ricardo Der Haroutiounian, diretor da Semapi.\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>O Abril Verde vai muito al\u00e9m de uma cor no calend\u00e1rio. Simboliza uma causa urgente e essencial: a prote\u00e7\u00e3o da vida dos trabalhadores.\u00a0\u00a0 Para criar a\u00e7\u00f5es eficazes em seguran\u00e7a do trabalho, \u00e9 fundamental compreender n\u00e3o apenas o objetivo da campanha, mas tamb\u00e9m sua origem e o que ela representa.\u00a0 A trag\u00e9dia Em novembro de 1968, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":445,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/es\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/abril-verde-conheca-a-historia-por-tras-da-campanha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"O Abril Verde vai muito al\u00e9m de uma cor no calend\u00e1rio. Simboliza uma causa urgente e essencial: a prote\u00e7\u00e3o da vida dos trabalhadores.\u00a0\u00a0 Para criar a\u00e7\u00f5es eficazes em seguran\u00e7a do trabalho, \u00e9 fundamental compreender n\u00e3o apenas o objetivo da campanha, mas tamb\u00e9m sua origem e o que ela representa.\u00a0 A trag\u00e9dia Em novembro de 1968, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/abril-verde-conheca-a-historia-por-tras-da-campanha\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-25T13:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T13:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha\",\"datePublished\":\"2025-04-25T13:57:01+00:00\",\"dateModified\":\"2025-04-25T13:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mina2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/\",\"name\":\"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mina2.jpg\",\"datePublished\":\"2025-04-25T13:57:01+00:00\",\"dateModified\":\"2025-04-25T13:57:48+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/abril-verde-conheca-a-historia-por-tras-da-campanha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mina2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/mina2.jpg\",\"width\":1024,\"height\":578,\"caption\":\"mina\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/abril-verde-conheca-a-historia-por-tras-da-campanha\/","og_locale":"es_ES","og_type":"article","og_title":"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI","og_description":"O Abril Verde vai muito al\u00e9m de uma cor no calend\u00e1rio. Simboliza uma causa urgente e essencial: a prote\u00e7\u00e3o da vida dos trabalhadores.\u00a0\u00a0 Para criar a\u00e7\u00f5es eficazes em seguran\u00e7a do trabalho, \u00e9 fundamental compreender n\u00e3o apenas o objetivo da campanha, mas tamb\u00e9m sua origem e o que ela representa.\u00a0 A trag\u00e9dia Em novembro de 1968, [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/abril-verde-conheca-a-historia-por-tras-da-campanha\/","og_site_name":"SEMAPI","article_published_time":"2025-04-25T13:57:01+00:00","article_modified_time":"2025-04-25T13:57:48+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketing","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha","datePublished":"2025-04-25T13:57:01+00:00","dateModified":"2025-04-25T13:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/"},"wordCount":368,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/","url":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/","name":"Abril Verde: conhe\u00e7a a hist\u00f3ria por tr\u00e1s da campanha - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","datePublished":"2025-04-25T13:57:01+00:00","dateModified":"2025-04-25T13:57:48+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/abril-verde-conheca-a-historia-por-tras-da-campanha\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/mina2.jpg","width":1024,"height":578,"caption":"mina"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/es\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3477"}],"version-history":[{"count":5,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3477\/revisions"}],"predecessor-version":[{"id":3483,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3477\/revisions\/3483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3481"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}