{"id":3463,"date":"2025-04-23T10:11:10","date_gmt":"2025-04-23T13:11:10","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3463"},"modified":"2025-04-23T10:11:10","modified_gmt":"2025-04-23T13:11:10","slug":"case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/","title":{"rendered":"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3463\" class=\"elementor elementor-3463\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0d5bf9 e-flex e-con-boxed e-con e-parent\" data-id=\"a0d5bf9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4af168 elementor-widget elementor-widget-text-editor\" data-id=\"c4af168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW248546064 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW248546064 BCX0\" data-ccp-parastyle=\"heading 3\">O Desafio: Controle manual e falta de efici\u00eancia<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d996c44 e-flex e-con-boxed e-con e-parent\" data-id=\"d996c44\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6ec8e0 elementor-widget elementor-widget-text-editor\" data-id=\"c6ec8e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW62409702 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW62409702 BCX0\">Antes da implementa\u00e7\u00e3o do MANTec, a rotina de manuten\u00e7\u00e3o da transportadora era marcada por processos manuais, controle em planilhas e uma pilha crescente de pap\u00e9is. A gest\u00e3o de manuten\u00e7\u00e3o e os custos associados eram monitorados por Excel, o que comprometia a visibilidade, a agilidade e a precis\u00e3o das informa\u00e7\u00f5es.<\/span><\/span><span class=\"EOP SCXW62409702 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1389a3 e-flex e-con-boxed e-con e-parent\" data-id=\"d1389a3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb67bc elementor-widget elementor-widget-text-editor\" data-id=\"bfb67bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW20681228 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW20681228 BCX0\" data-ccp-parastyle=\"heading 3\">A Escolha: Reduzir o papel, otimizar a opera\u00e7\u00e3o<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3b0877 e-flex e-con-boxed e-con e-parent\" data-id=\"f3b0877\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98a6866 elementor-widget elementor-widget-text-editor\" data-id=\"98a6866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW121127722 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW121127722 BCX0\">A empresa buscava uma solu\u00e7\u00e3o que pudesse eliminar os controles manuais, digitalizar os processos e melhorar a aloca\u00e7\u00e3o de recursos. A escolha pelo <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW121127722 BCX0\">MANTec<\/span><span class=\"NormalTextRun SCXW121127722 BCX0\"> veio da necessidade de transformar o modelo de <b>gest\u00e3o da manuten\u00e7\u00e3o, tornando-o mais moderno, \u00e1gil e alinhado \u00e0s demandas operacionais.<\/b><\/span><\/span><span class=\"EOP SCXW121127722 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\"><b>\u00a0<\/b><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2aa0cb e-flex e-con-boxed e-con e-parent\" data-id=\"b2aa0cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cea00b6 elementor-widget elementor-widget-text-editor\" data-id=\"cea00b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW74039817 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW74039817 BCX0\" data-ccp-parastyle=\"heading 3\">O Come\u00e7o: Superando resist\u00eancias<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6b4cce e-flex e-con-boxed e-con e-parent\" data-id=\"e6b4cce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc21bcd elementor-widget elementor-widget-text-editor\" data-id=\"fc21bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">A principal barreira inicial foi a <b>mudan\u00e7a de cultura<\/b>. A equipe estava acostumada ao modelo antigo e resistiu \u00e0 digitaliza\u00e7\u00e3o. Al\u00e9m disso, o sistema precisou ser adaptado \u00e0s necessidades espec\u00edficas da opera\u00e7\u00e3o da transportadora.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">&nbsp;<\/span><\/p>\n<p><span data-contrast=\"auto\">A <b>supera\u00e7\u00e3o veio atrav\u00e9s de conversas constantes, treinamentos direcionados e do suporte cont\u00ednuo da equipe SEMAPI.<\/b> Com esse apoio, foi poss\u00edvel integrar o sistema \u00e0 rotina da equipe operacional.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">&nbsp;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81c3b2e e-flex e-con-boxed e-con e-parent\" data-id=\"81c3b2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0610270 elementor-widget elementor-widget-text-editor\" data-id=\"0610270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW79542133 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW79542133 BCX0\" data-ccp-parastyle=\"heading 3\">Os Resultados: Mobilidade, agilidade e mais assertividade<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6df839f e-flex e-con-boxed e-con e-parent\" data-id=\"6df839f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e81aa3c elementor-widget elementor-widget-text-editor\" data-id=\"e81aa3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">A implanta\u00e7\u00e3o do MANTec trouxe mudan\u00e7as significativas no dia a dia da empresa. Os checklists em papel foram substitu\u00eddos por pedidos de trabalho via celular, tornando o processo mais r\u00e1pido e assertivo. A gest\u00e3o passou a ter acesso quase em tempo real aos problemas nos equipamentos, possibilitando a\u00e7\u00f5es mais \u00e1geis e preventivas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Segundo o respons\u00e1vel pela manuten\u00e7\u00e3o da transportadora:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52b86ae e-flex e-con-boxed e-con e-parent\" data-id=\"52b86ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b7b79 elementor-widget elementor-widget-text-editor\" data-id=\"c8b7b79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><em><strong><span class=\"TextRun SCXW196253443 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW196253443 BCX0\">\u201cAntes eu ficava exausto com o ac\u00famulo de pap\u00e9is. Ainda n\u00e3o eliminei completamente, mas com o <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW196253443 BCX0\">MANTec<\/span><span class=\"NormalTextRun SCXW196253443 BCX0\"> consegui respirar. O servi\u00e7o aumentou, mas o risco de erro caiu drasticamente.\u201d<\/span><\/span><span class=\"EOP SCXW196253443 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/strong><\/em><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89cffcc e-flex e-con-boxed e-con e-parent\" data-id=\"89cffcc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5affc2b elementor-widget elementor-widget-text-editor\" data-id=\"5affc2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW5374971 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW5374971 BCX0\" data-ccp-parastyle=\"heading 3\">Indicadores de Sucesso<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d87409 e-flex e-con-boxed e-con e-parent\" data-id=\"2d87409\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef19fcb elementor-widget elementor-widget-text-editor\" data-id=\"ef19fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Custo de manuten\u00e7\u00e3o x faturamento:<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Antes da implanta\u00e7\u00e3o: 8,35%<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Em 2019: redu\u00e7\u00e3o simb\u00f3lica para 8,3%<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Em 2020: ganho de 5 pontos percentuais, com maior maturidade da equipe<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6df7d1 e-flex e-con-boxed e-con e-parent\" data-id=\"e6df7d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e09426 elementor-widget elementor-widget-image\" data-id=\"6e09426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"646\" height=\"567\" src=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3464\" alt=\"grafico\" srcset=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-1.jpg 646w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-1-300x263.jpg 300w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-1-14x12.jpg 14w\" sizes=\"(max-width: 646px) 100vw, 646px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6fc8a4 e-flex e-con-boxed e-con e-parent\" data-id=\"b6fc8a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec61863 elementor-widget elementor-widget-text-editor\" data-id=\"ec61863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Preventivas realizadas x previstas:<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">2018 (antes do sistema): 68% de execu\u00e7\u00e3o<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">2019 (com MANTec): 70% de execu\u00e7\u00e3o<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">2020: 82% de execu\u00e7\u00e3o<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e97f20 e-flex e-con-boxed e-con e-parent\" data-id=\"7e97f20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ffa4a5 elementor-widget elementor-widget-image\" data-id=\"2ffa4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"565\" src=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-2.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3465\" alt=\"grafico\" srcset=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-2.jpg 750w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-2-300x226.jpg 300w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/grafico-2-16x12.jpg 16w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1c187b e-flex e-con-boxed e-con e-parent\" data-id=\"a1c187b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba322db elementor-widget elementor-widget-text-editor\" data-id=\"ba322db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW32879603 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW32879603 BCX0\">Esses dados evidenciam a evolu\u00e7\u00e3o significativa na efici\u00eancia da manuten\u00e7\u00e3o e no planejamento operacional.<\/span><\/span><span class=\"EOP SCXW32879603 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e05c46 e-flex e-con-boxed e-con e-parent\" data-id=\"6e05c46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ab822e elementor-widget elementor-widget-text-editor\" data-id=\"1ab822e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span class=\"TextRun SCXW68305849 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW68305849 BCX0\" data-ccp-parastyle=\"heading 3\">A Transforma\u00e7\u00e3o: Gest\u00e3o mais inteligente, erros reduzidos<\/span><\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e743bad e-flex e-con-boxed e-con e-parent\" data-id=\"e743bad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f02db1 elementor-widget elementor-widget-text-editor\" data-id=\"0f02db1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW215217615 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW215217615 BCX0\">Hoje, a transportadora colhe os frutos de um processo mais fluido, organizado e inteligente. A manuten\u00e7\u00e3o passou a ser um setor estrat\u00e9gico, com dados em tempo real, decis\u00f5es embasadas e controle digital. O pr\u00f3ximo passo \u00e9 concluir o treinamento para que 100% das ordens de servi\u00e7o e rotas sejam finalizadas via mobile \u2014 um avan\u00e7o que j\u00e1 est\u00e1 no radar da equipe.<\/span><\/span><span class=\"EOP SCXW215217615 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68ca898 e-flex e-con-boxed e-con e-parent\" data-id=\"68ca898\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b4659f elementor-widget elementor-widget-text-editor\" data-id=\"2b4659f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span class=\"TextRun SCXW229246051 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW229246051 BCX0\">Voc\u00ea tamb\u00e9m quer transformar a gest\u00e3o de manuten\u00e7\u00e3o da sua empresa?<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW229246051 BCX0\"><span class=\"SCXW229246051 BCX0\">\u00a0<\/span><br class=\"SCXW229246051 BCX0\" \/><\/span><span class=\"TextRun SCXW229246051 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW229246051 BCX0\"> Fale com a SEMAPI e conhe\u00e7a o <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW229246051 BCX0\">MANTec<\/span><span class=\"NormalTextRun SCXW229246051 BCX0\"> na pr\u00e1tica.<\/span><\/span><\/b><span class=\"LineBreakBlob BlobObject DragDrop SCXW229246051 BCX0\" style=\"font-weight: bold;\"><br class=\"SCXW229246051 BCX0\" \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-910db15 e-flex e-con-boxed e-con e-parent\" data-id=\"910db15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19bf340 elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"19bf340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O Desafio: Controle manual e falta de efici\u00eancia Antes da implementa\u00e7\u00e3o do MANTec, a rotina de manuten\u00e7\u00e3o da transportadora era marcada por processos manuais, controle em planilhas e uma pilha crescente de pap\u00e9is. A gest\u00e3o de manuten\u00e7\u00e3o e os custos associados eram monitorados por Excel, o que comprometia a visibilidade, a agilidade e a precis\u00e3o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":3473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":15,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","author_info":{"display_name":"B\u00e1rbarah Andrade Fernandes Machado","author_link":"https:\/\/semapi.com.br\/es\/author\/bafernandes\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"O Desafio: Controle manual e falta de efici\u00eancia Antes da implementa\u00e7\u00e3o do MANTec, a rotina de manuten\u00e7\u00e3o da transportadora era marcada por processos manuais, controle em planilhas e uma pilha crescente de pap\u00e9is. A gest\u00e3o de manuten\u00e7\u00e3o e os custos associados eram monitorados por Excel, o que comprometia a visibilidade, a agilidade e a precis\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T13:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/\"},\"author\":{\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\"},\"headline\":\"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI\",\"datePublished\":\"2025-04-23T13:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_595732921.jpeg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/\",\"name\":\"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_595732921.jpeg\",\"datePublished\":\"2025-04-23T13:11:10+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_595732921.jpeg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/AdobeStock_595732921.jpeg\",\"width\":800,\"height\":533,\"caption\":\"AdobeStock\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\",\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/bafernandes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/","og_locale":"es_ES","og_type":"article","og_title":"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI","og_description":"O Desafio: Controle manual e falta de efici\u00eancia Antes da implementa\u00e7\u00e3o do MANTec, a rotina de manuten\u00e7\u00e3o da transportadora era marcada por processos manuais, controle em planilhas e uma pilha crescente de pap\u00e9is. A gest\u00e3o de manuten\u00e7\u00e3o e os custos associados eram monitorados por Excel, o que comprometia a visibilidade, a agilidade e a precis\u00e3o [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/","og_site_name":"SEMAPI","article_published_time":"2025-04-23T13:11:10+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","type":"image\/jpeg"}],"author":"B\u00e1rbarah Andrade Fernandes Machado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"B\u00e1rbarah Andrade Fernandes Machado","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/"},"author":{"name":"B\u00e1rbarah Andrade Fernandes Machado","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e"},"headline":"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI","datePublished":"2025-04-23T13:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/"},"wordCount":497,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/","url":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/","name":"Case de Sucesso | MANTec na pr\u00e1tica: Como uma transportadora transformou sua gest\u00e3o de manuten\u00e7\u00e3o e reduziu custos com a ajuda da SEMAPI - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","datePublished":"2025-04-23T13:11:10+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/case-de-sucesso-mantec-na-pratica-como-uma-transportadora-transformou-sua-gestao-de-manutencao-e-reduziu-custos-com-a-ajuda-da-semapi\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/04\/AdobeStock_595732921.jpeg","width":800,"height":533,"caption":"AdobeStock"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e","name":"B\u00e1rbarah Andrade Fernandes Machado","url":"https:\/\/semapi.com.br\/es\/author\/bafernandes\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=3463"}],"version-history":[{"count":4,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3463\/revisions"}],"predecessor-version":[{"id":3474,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/3463\/revisions\/3474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/3473"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=3463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=3463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=3463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}