{"id":2839,"date":"2024-08-13T10:39:35","date_gmt":"2024-08-13T13:39:35","guid":{"rendered":"https:\/\/semapi.com.br\/?p=2839"},"modified":"2024-08-13T10:39:35","modified_gmt":"2024-08-13T13:39:35","slug":"deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/es\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/","title":{"rendered":"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2839\" class=\"elementor elementor-2839\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12b928c e-flex e-con-boxed e-con e-parent\" data-id=\"12b928c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d26895e elementor-widget elementor-widget-text-editor\" data-id=\"d26895e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW78313842 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW78313842 BCX0\">A SEMAPI emprega tecnologia inovadora para detectar vazamentos de hidrocarbonetos, metano (CH\u2084) e outras emiss\u00f5es de compostos org\u00e2nicos vol\u00e1teis (COV) em diversos setores industriais, incluindo petr\u00f3leo e g\u00e1s. <b>Como a \u00fanica empresa de manuten\u00e7\u00e3o no Brasil a possuir essa tecnologia de ponta<\/b>, exploramos como essa c\u00e2mera funciona e os benef\u00edcios que ela oferece.<\/span><\/span><span class=\"EOP SCXW78313842 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">&nbsp;<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-691528c e-flex e-con-boxed e-con e-parent\" data-id=\"691528c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08afa63 elementor-widget elementor-widget-text-editor\" data-id=\"08afa63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong><span class=\"TextRun SCXW105363235 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW105363235 BCX0\" data-ccp-parastyle=\"Subtitle\">Como Funciona?<\/span><\/span><\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b202072 e-flex e-con-boxed e-con e-parent\" data-id=\"b202072\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b6056 elementor-widget elementor-widget-text-editor\" data-id=\"68b6056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Utilizamos tecnologia de\u202f<\/span><b><span data-contrast=\"auto\">Imaging Optical Gas<\/span><\/b><span data-contrast=\"auto\">\u202f(OGI) para visualizar gases invis\u00edveis aos olhos humanos. Aqui est\u00e3o os principais pontos:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Matriz de plano focal avan\u00e7ada<\/span><\/b><span data-contrast=\"auto\">: A c\u00e2mera possui uma matriz de plano focal de \u00faltima gera\u00e7\u00e3o, que detecta energia infravermelha absorvida por vazamentos de g\u00e1s hidrocarboneto.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Processamento de imagem<\/span><\/b><span data-contrast=\"auto\">: As imagens capturadas s\u00e3o processadas e aprimoradas pelo modo de sensibilidade avan\u00e7ado, destacando claramente a presen\u00e7a de gases contra fundos estacion\u00e1rios.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Seguran\u00e7a e economia<\/span><\/b><span data-contrast=\"auto\">: Nossa c\u00e2mera permite que operadores detectem vazamentos de uma dist\u00e2ncia segura, evitando riscos \u00e0 sa\u00fade e reduzindo perdas financeiras.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cb36d9 e-flex e-con-boxed e-con e-parent\" data-id=\"6cb36d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5adfcb8 elementor-widget elementor-widget-text-editor\" data-id=\"5adfcb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong><span class=\"TextRun SCXW244055689 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW244055689 BCX0\" data-ccp-parastyle=\"Subtitle\">Beneficios<\/span><\/span><\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98cc89b e-flex e-con-boxed e-con e-parent\" data-id=\"98cc89b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5d1152 elementor-widget elementor-widget-text-editor\" data-id=\"d5d1152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><span data-contrast=\"auto\">Varredura r\u00e1pida<\/span><\/b><span data-contrast=\"auto\">: A c\u00e2mera pode digitalizar \u00e1reas amplas rapidamente, identificando vazamentos de forma eficiente.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Inspe\u00e7\u00e3o em locais de dif\u00edcil acesso<\/span><\/b><span data-contrast=\"auto\">: Alcance \u00e1reas que seriam inacess\u00edveis com ferramentas de medi\u00e7\u00e3o tradicionais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p><b><span data-contrast=\"auto\">Seguran\u00e7a do operador<\/span><\/b><span data-contrast=\"auto\">: Ao detectar emiss\u00f5es de uma dist\u00e2ncia segura, a c\u00e2mera melhora a seguran\u00e7a dos profissionais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a7a222 e-flex e-con-boxed e-con e-parent\" data-id=\"4a7a222\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d9ae8a elementor-widget elementor-widget-text-editor\" data-id=\"8d9ae8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong><span class=\"TextRun SCXW236623530 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW236623530 BCX0\" data-ccp-parastyle=\"Subtitle\">A <\/span><span class=\"NormalTextRun SCXW236623530 BCX0\" data-ccp-parastyle=\"Subtitle\">Import\u00e2ncia da C\u00e2mera para detec\u00e7\u00e3o de vazamentos e prote\u00e7\u00e3o ambiental<\/span><\/span><span class=\"EOP SCXW236623530 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-003bf9d e-flex e-con-boxed e-con e-parent\" data-id=\"003bf9d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d2a58e elementor-widget elementor-widget-text-editor\" data-id=\"9d2a58e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">A SEMAPI emprega a inovadora tecnologia de\u202f<\/span><b><span data-contrast=\"auto\">Imaging Optical Gas (OGI)<\/span><\/b><span data-contrast=\"auto\">\u202fpara detectar vazamentos de gases como metano (CH\u2084) e compostos org\u00e2nicos vol\u00e1teis (COV), essencial para setores como petr\u00f3leo e g\u00e1s. Nossa c\u00e2mera, com sua avan\u00e7ada matriz de plano focal, identifica a energia infravermelha emitida por hidrocarbonetos, permitindo uma visualiza\u00e7\u00e3o clara dos gases que s\u00e3o invis\u00edveis a olho nu.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1445a91 e-flex e-con-boxed e-con e-parent\" data-id=\"1445a91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3338773 elementor-widget elementor-widget-text-editor\" data-id=\"3338773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Transforme sua manuten\u00e7\u00e3o com a SEMAPI<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbcd183 elementor-widget elementor-widget-text-editor\" data-id=\"cbcd183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW99491433 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99491433 BCX0\">A c\u00e2mera \u00e9 vital para a ind\u00fastria, n\u00e3o s\u00f3 por melhorar a seguran\u00e7a e <\/span><\/span><span class=\"TextRun SCXW99491433 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99491433 BCX0\">reduzir perdas financeiras<\/span><\/span><span class=\"TextRun SCXW99491433 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99491433 BCX0\">, mas tamb\u00e9m por seu papel crucial na <\/span><\/span><span class=\"TextRun SCXW99491433 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99491433 BCX0\">preserva\u00e7\u00e3o ambiental<\/span><\/span><span class=\"TextRun SCXW99491433 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW99491433 BCX0\">. Sua ado\u00e7\u00e3o representa um passo importante para opera\u00e7\u00f5es mais seguras e sustent\u00e1veis, al\u00e9m de ser uma ferramenta estrat\u00e9gica na luta contra as mudan\u00e7as clim\u00e1ticas.<\/span><\/span><span class=\"EOP SCXW99491433 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p><p>Com a SEMAPI, sua ind\u00fastria pode se beneficiar das mais recentes inova\u00e7\u00f5es tecnol\u00f3gicas para detectar vazamentos de g\u00e1s de forma eficiente e segura. N\u00e3o perca a oportunidade de otimizar suas opera\u00e7\u00f5es e garantir a detec\u00e7\u00e3o precoce de vazamentos. Entre em contato conosco e descubra como podemos transformar a manuten\u00e7\u00e3o em sua empresa com essa solu\u00e7\u00e3o de ponta!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9664f0 e-flex e-con-boxed e-con e-parent\" data-id=\"a9664f0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>A SEMAPI emprega tecnologia inovadora para detectar vazamentos de hidrocarbonetos, metano (CH\u2084) e outras emiss\u00f5es de compostos org\u00e2nicos vol\u00e1teis (COV) em diversos setores industriais, incluindo petr\u00f3leo e g\u00e1s. Como a \u00fanica empresa de manuten\u00e7\u00e3o no Brasil a possuir essa tecnologia de ponta, exploramos como essa c\u00e2mera funciona e os benef\u00edcios que ela oferece. Como Funciona? [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":2869,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":7,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-2839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","author_info":{"display_name":"B\u00e1rbarah Andrade Fernandes Machado","author_link":"https:\/\/semapi.com.br\/es\/author\/bafernandes\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/es\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"A SEMAPI emprega tecnologia inovadora para detectar vazamentos de hidrocarbonetos, metano (CH\u2084) e outras emiss\u00f5es de compostos org\u00e2nicos vol\u00e1teis (COV) em diversos setores industriais, incluindo petr\u00f3leo e g\u00e1s. Como a \u00fanica empresa de manuten\u00e7\u00e3o no Brasil a possuir essa tecnologia de ponta, exploramos como essa c\u00e2mera funciona e os benef\u00edcios que ela oferece. Como Funciona? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/es\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T13:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/\"},\"author\":{\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\"},\"headline\":\"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI\",\"datePublished\":\"2024-08-13T13:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/\"},\"wordCount\":462,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/CAPA-BLOG.png\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/\",\"name\":\"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/CAPA-BLOG.png\",\"datePublished\":\"2024-08-13T13:39:35+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/CAPA-BLOG.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/CAPA-BLOG.png\",\"width\":2560,\"height\":1707,\"caption\":\"detec\u00e7\u00e3o de g\u00e1s em ind\u00fastria\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\",\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/es\\\/author\\\/bafernandes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/es\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/","og_locale":"es_ES","og_type":"article","og_title":"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI","og_description":"A SEMAPI emprega tecnologia inovadora para detectar vazamentos de hidrocarbonetos, metano (CH\u2084) e outras emiss\u00f5es de compostos org\u00e2nicos vol\u00e1teis (COV) em diversos setores industriais, incluindo petr\u00f3leo e g\u00e1s. Como a \u00fanica empresa de manuten\u00e7\u00e3o no Brasil a possuir essa tecnologia de ponta, exploramos como essa c\u00e2mera funciona e os benef\u00edcios que ela oferece. Como Funciona? [&hellip;]","og_url":"https:\/\/semapi.com.br\/es\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/","og_site_name":"SEMAPI","article_published_time":"2024-08-13T13:39:35+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","type":"image\/png"}],"author":"B\u00e1rbarah Andrade Fernandes Machado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"B\u00e1rbarah Andrade Fernandes Machado","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/"},"author":{"name":"B\u00e1rbarah Andrade Fernandes Machado","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e"},"headline":"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI","datePublished":"2024-08-13T13:39:35+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/"},"wordCount":462,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","articleSection":["sem categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/","url":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/","name":"Transforme a detec\u00e7\u00e3o de vazamentos de g\u00e1s com a tecnologia G\u00e1s Fire da SEMAPI - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","datePublished":"2024-08-13T13:39:35+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/deteccao-de-vazamentos-de-gas-tecnologia-gasfire-semapi\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2024\/08\/CAPA-BLOG.png","width":2560,"height":1707,"caption":"detec\u00e7\u00e3o de g\u00e1s em ind\u00fastria"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e","name":"B\u00e1rbarah Andrade Fernandes Machado","url":"https:\/\/semapi.com.br\/es\/author\/bafernandes\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/2839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/comments?post=2839"}],"version-history":[{"count":24,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/2839\/revisions"}],"predecessor-version":[{"id":2866,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/posts\/2839\/revisions\/2866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media\/2869"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/media?parent=2839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/categories?post=2839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/es\/wp-json\/wp\/v2\/tags?post=2839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}