{"id":5581,"date":"2026-05-27T11:09:00","date_gmt":"2026-05-27T14:09:00","guid":{"rendered":"https:\/\/semapi.com.br\/?p=5581"},"modified":"2026-05-20T12:23:05","modified_gmt":"2026-05-20T15:23:05","slug":"gestao-de-ativos-biscoitos-bela-vista","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/en\/gestao-de-ativos-biscoitos-bela-vista\/","title":{"rendered":"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Na ind\u00fastria aliment\u00edcia, onde produtividade, qualidade e continuidade operacional caminham lado a lado, a gest\u00e3o de ativos deixou de ser apenas uma atividade de suporte e passou a ocupar um papel estrat\u00e9gico dentro das opera\u00e7\u00f5es industriais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paradas inesperadas, falhas recorrentes e dificuldade no controle das manuten\u00e7\u00f5es impactam diretamente a produ\u00e7\u00e3o, os custos e at\u00e9 a capacidade de atender demandas do mercado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse cen\u00e1rio, empresas que investem em planejamento, controle e intelig\u00eancia operacional conseguem transformar a manuten\u00e7\u00e3o em uma vantagem competitiva.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi justamente buscando mais previsibilidade e efici\u00eancia que a Biscoitos Bela Vista adotou <a href=\"https:\/\/semapi.com.br\/en\/mantec\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/mantec\/\" target=\"_blank\" rel=\"noreferrer noopener\">o\u00a0MANTec<\/a>, sistema inteligente de gest\u00e3o da manuten\u00e7\u00e3o da SEMAPI. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A solu\u00e7\u00e3o passou a integrar informa\u00e7\u00f5es cr\u00edticas da opera\u00e7\u00e3o, oferecendo mais controle sobre os ativos industriais e apoiando decis\u00f5es mais r\u00e1pidas e assertivas.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O desafio da gest\u00e3o de ativos na ind\u00fastria<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em ambientes industriais, especialmente no setor aliment\u00edcio, a gest\u00e3o de ativos precisa garantir que equipamentos operem com m\u00e1xima confiabilidade e <a href=\"https:\/\/semapi.com.br\/en\/case-no-agronegocio-manutencao-preditiva\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/case-no-agronegocio-manutencao-preditiva\/\" target=\"_blank\" rel=\"noreferrer noopener\">disponibilidade<\/a>. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, muitos setores ainda enfrentam dificuldades relacionadas \u00e0 descentraliza\u00e7\u00e3o de informa\u00e7\u00f5es, falta de hist\u00f3rico t\u00e9cnico e baixa rastreabilidade das interven\u00e7\u00f5es realizadas nos equipamentos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem um sistema estruturado, o planejamento das manuten\u00e7\u00f5es tende a ser mais reativo, aumentando os riscos de paradas inesperadas e elevando os custos operacionais.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi diante desse cen\u00e1rio que a Biscoitos Bela Vista buscou uma solu\u00e7\u00e3o capaz de melhorar o controle das manuten\u00e7\u00f5es e trazer mais intelig\u00eancia para a gest\u00e3o de ativos da opera\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como o&nbsp;MANTec&nbsp;transformou a rotina da manuten\u00e7\u00e3o<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com a implanta\u00e7\u00e3o do\u00a0MANTec, a empresa passou a centralizar informa\u00e7\u00f5es importantes da manuten\u00e7\u00e3o em um \u00fanico ambiente. Integrando ordens de servi\u00e7o, hist\u00f3rico de equipamentos, planejamento de interven\u00e7\u00f5es e acompanhamento das paradas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Adriano Sena dos Santos, Planejador de Manuten\u00e7\u00e3o da Biscoitos Bela Vista, os ganhos come\u00e7aram a aparecer logo nas primeiras etapas de utiliza\u00e7\u00e3o do sistema.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O controle das ordens de servi\u00e7o e o acesso r\u00e1pido ao hist\u00f3rico completo dos ativos permitiram uma vis\u00e3o mais estrat\u00e9gica da opera\u00e7\u00e3o, tornando a tomada de decis\u00e3o mais segura e baseada em dados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a equipe passou a <a href=\"https:\/\/semapi.com.br\/en\/analise-de-falhas\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/analise-de-falhas\/\" target=\"_blank\" rel=\"noreferrer noopener\">analisar com mais precis\u00e3o as ocorr\u00eancias anteriores<\/a> de manuten\u00e7\u00e3o, identificando padr\u00f5es de falhas e oportunidades de melhoria cont\u00ednua.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa mudan\u00e7a elevou o n\u00edvel de maturidade da manuten\u00e7\u00e3o dentro da empresa, reduzindo a depend\u00eancia de informa\u00e7\u00f5es dispersas e tornando os processos mais organizados e previs\u00edveis.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Hist\u00f3rico de manuten\u00e7\u00e3o e planejamento mais eficiente<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos pontos de maior impacto na opera\u00e7\u00e3o foi a utiliza\u00e7\u00e3o do hist\u00f3rico de pe\u00e7as, interven\u00e7\u00f5es e servi\u00e7os anteriores registrados no sistema.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com todas essas informa\u00e7\u00f5es organizadas, as paradas programadas passaram a ser planejadas com mais anteced\u00eancia e precis\u00e3o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso permitiu que a equipe verificasse previamente a disponibilidade de pe\u00e7as, ferramentas e recursos necess\u00e1rios para cada atividade.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O resultado foi uma redu\u00e7\u00e3o significativa de imprevistos durante as manuten\u00e7\u00f5es preventivas.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cDevido ao hist\u00f3rico de pe\u00e7as registradas nas ordens anteriores, podemos analisar a parada programada com todas as pe\u00e7as e ferramentas dispon\u00edveis para a execu\u00e7\u00e3o do servi\u00e7o. Assim, n\u00e3o tivemos surpresas nas paradas preventivas\u201d, destaca Adriano Sena.\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esse tipo de controle \u00e9 essencial dentro de uma estrat\u00e9gia eficiente de gest\u00e3o de ativos, pois reduz desperd\u00edcios, evita atrasos e melhora o aproveitamento da equipe de manuten\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a previsibilidade operacional contribui diretamente para o aumento da confiabilidade dos equipamentos e para a estabilidade da produ\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gest\u00e3o de ativos com foco em confiabilidade operacional<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Outro benef\u00edcio importante foi a estrutura\u00e7\u00e3o dos planos de revis\u00e3o dos equipamentos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o apoio do&nbsp;MANTec, a Biscoitos Bela Vista conseguiu definir periodicidades espec\u00edficas para cada ativo, respeitando as caracter\u00edsticas operacionais e a criticidade de cada equipamento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa abordagem tornou a manuten\u00e7\u00e3o mais estrat\u00e9gica e eficiente, permitindo que as interven\u00e7\u00f5es acontecessem no momento ideal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na pr\u00e1tica, isso contribuiu para:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>redu\u00e7\u00e3o de falhas inesperadas;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>aumento da vida \u00fatil dos equipamentos;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>maior confiabilidade operacional;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>otimiza\u00e7\u00e3o do tempo das equipes;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>redu\u00e7\u00e3o de custos com manuten\u00e7\u00e3o corretiva.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro de uma estrat\u00e9gia moderna de gest\u00e3o de ativos, a manuten\u00e7\u00e3o preventiva e preditiva desempenha um papel fundamental justamente por permitir o monitoramento cont\u00ednuo da condi\u00e7\u00e3o dos equipamentos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em vez de atuar ap\u00f3s uma falha, a empresa passa a trabalhar de forma preventiva, reduzindo riscos e aumentando a disponibilidade operacional dos ativos industriais.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mais agilidade e efici\u00eancia com o&nbsp;MANTec&nbsp;4.0<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com a chegada da <a href=\"https:\/\/semapi.com.br\/en\/mantec-4-0-entenda-como-revolucionar-a-gestao-de-manutencao-industrial\/\" type=\"link\" id=\"https:\/\/semapi.com.br\/mantec-4-0-entenda-como-revolucionar-a-gestao-de-manutencao-industrial\/\" target=\"_blank\" rel=\"noreferrer noopener\">vers\u00e3o 4.0 do\u00a0MANTec<\/a>, a experi\u00eancia da equipe ganhou ainda mais velocidade e praticidade.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nova interface tornou a navega\u00e7\u00e3o mais intuitiva e facilitou o acesso \u00e0s informa\u00e7\u00f5es operacionais, permitindo an\u00e1lises mais r\u00e1pidas e maior agilidade no acompanhamento das manuten\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a equipe da Biscoitos Bela Vista, a evolu\u00e7\u00e3o do sistema trouxe melhorias importantes \u00e0 opera\u00e7\u00e3o, especialmente na an\u00e1lise de dados, no acompanhamento dos equipamentos e na execu\u00e7\u00e3o das manuten\u00e7\u00f5es preventivas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa facilidade de acesso \u00e0s informa\u00e7\u00f5es impacta diretamente a produtividade das equipes e fortalece a tomada de decis\u00e3o baseada em indicadores e dados hist\u00f3ricos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em opera\u00e7\u00f5es industriais cada vez mais orientadas por desempenho, tecnologia e confiabilidade, contar com um sistema inteligente de gest\u00e3o de ativos se tornou um diferencial competitivo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Os resultados obtidos pela Biscoitos Bela Vista<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com o apoio do&nbsp;MANTec, a Biscoitos Bela Vista conquistou melhorias importantes na gest\u00e3o da manuten\u00e7\u00e3o e no controle dos ativos industriais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os principais resultados percebidos pela empresa est\u00e3o:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mais previsibilidade nas paradas programadas;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>redu\u00e7\u00e3o de imprevistos durante manuten\u00e7\u00f5es preventivas;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>decis\u00f5es mais r\u00e1pidas e embasadas em dados;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>aumento da confiabilidade operacional;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>maior controle sobre hist\u00f3rico e interven\u00e7\u00f5es;\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>equipamentos com maior vida \u00fatil.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Mais do que um sistema de manuten\u00e7\u00e3o, o&nbsp;MANTec&nbsp;passou a atuar como parte estrat\u00e9gica da opera\u00e7\u00e3o, conectando planejamento, execu\u00e7\u00e3o e an\u00e1lise em uma \u00fanica plataforma.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tecnologia e gest\u00e3o de ativos como diferencial competitivo<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A transforma\u00e7\u00e3o digital da manuten\u00e7\u00e3o industrial j\u00e1 \u00e9 uma realidade em empresas que buscam mais efici\u00eancia, previsibilidade e competitividade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, investir em gest\u00e3o de ativos deixou de ser apenas uma necessidade operacional e passou a ser uma estrat\u00e9gia essencial para garantir produtividade, reduzir custos e aumentar a confiabilidade dos processos industriais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com solu\u00e7\u00f5es inteligentes como o&nbsp;MANTec, empresas conseguem transformar dados operacionais em decis\u00f5es estrat\u00e9gicas, criando opera\u00e7\u00f5es mais organizadas, eficientes e preparadas para os desafios da ind\u00fastria moderna.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Na ind\u00fastria aliment\u00edcia, onde produtividade, qualidade e continuidade operacional caminham lado a lado, a gest\u00e3o de ativos deixou de ser apenas uma atividade de suporte e passou a ocupar um papel estrat\u00e9gico dentro das opera\u00e7\u00f5es industriais.&nbsp; Paradas inesperadas, falhas recorrentes e dificuldade no controle das manuten\u00e7\u00f5es impactam diretamente a produ\u00e7\u00e3o, os custos e at\u00e9 a [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":5339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":4,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-5581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/en\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0<\/title>\n<meta name=\"description\" content=\"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/en\/gestao-de-ativos-biscoitos-bela-vista\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0\" \/>\n<meta property=\"og:description\" content=\"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/en\/gestao-de-ativos-biscoitos-bela-vista\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T14:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0\",\"datePublished\":\"2026-05-27T14:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/\"},\"wordCount\":1203,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/case-biscoitos-bela-vista.png\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/\",\"name\":\"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/case-biscoitos-bela-vista.png\",\"datePublished\":\"2026-05-27T14:09:00+00:00\",\"description\":\"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/gestao-de-ativos-biscoitos-bela-vista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/case-biscoitos-bela-vista.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/case-biscoitos-bela-vista.png\",\"width\":1024,\"height\":576,\"caption\":\"Gest\u00e3o de ativos: case biscoitos bela vista\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0","description":"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/en\/gestao-de-ativos-biscoitos-bela-vista\/","og_locale":"en_US","og_type":"article","og_title":"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0","og_description":"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos","og_url":"https:\/\/semapi.com.br\/en\/gestao-de-ativos-biscoitos-bela-vista\/","og_site_name":"SEMAPI","article_published_time":"2026-05-27T14:09:00+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","type":"image\/png"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marketing","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0","datePublished":"2026-05-27T14:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/"},"wordCount":1203,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","articleSection":["sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/","url":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/","name":"Gest\u00e3o de ativos:\u00a0case de sucesso da\u00a0Biscoitos Bela Vista\u00a0","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","datePublished":"2026-05-27T14:09:00+00:00","description":"Com o MANTec, sistema de manuten\u00e7\u00e3o da SEMAPI, a Biscoitos Bela Vista eliminou surpresas e paradas inesperadas durante gest\u00e3o de ativos","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/gestao-de-ativos-biscoitos-bela-vista\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2026\/02\/case-biscoitos-bela-vista.png","width":1024,"height":576,"caption":"Gest\u00e3o de ativos: case biscoitos bela vista"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/en\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/5581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/comments?post=5581"}],"version-history":[{"count":3,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/5581\/revisions"}],"predecessor-version":[{"id":5584,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/5581\/revisions\/5584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media\/5339"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media?parent=5581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/categories?post=5581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/tags?post=5581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}