{"id":4813,"date":"2025-11-18T14:11:24","date_gmt":"2025-11-18T17:11:24","guid":{"rendered":"https:\/\/semapi.com.br\/?p=4813"},"modified":"2025-11-18T14:11:24","modified_gmt":"2025-11-18T17:11:24","slug":"semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/en\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/","title":{"rendered":"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo"},"content":{"rendered":"<p>Em ambientes industriais de alta performance, como o setor papeleiro, pequenas anomalias podem evoluir rapidamente para grandes problemas. Foi exatamente isso que a manuten\u00e7\u00e3o preditiva da SEMAPI conseguiu evitar neste caso: a falha de um rolamento cr\u00edtico em uma m\u00e1quina de papel, um evento que poderia gerar aproximadamente 7 horas <a href=\"https:\/\/semapi.com.br\/en\/em-apenas-seis-horas-manutencao-preditiva-preserva-4-200-toneladas-de-producao\/\">de parada n\u00e3o planejada<\/a> e preju\u00edzos significativos.<\/p>\n<p>Durante uma rotina de an\u00e1lise de vibra\u00e7\u00e3o, a equipe observou uma evolu\u00e7\u00e3o anormal na tend\u00eancia de vibra\u00e7\u00e3o em um dos mancais do equipamento. O comportamento do sinal chamava aten\u00e7\u00e3o principalmente em dois indicadores essenciais para diagn\u00f3stico de falhas em rolamentos:\u00a0acelera\u00e7\u00e3o\u00a0e\u00a0envelope de acelera\u00e7\u00e3o. A an\u00e1lise espectral confirmou componentes compat\u00edveis com defeito na\u00a0pista externa (BPFO), indicando que o rolamento estava entrando em um <a href=\"https:\/\/semapi.com.br\/en\/como-conectar-manutencao-e-compras-pode-transformar-sua-operacao\/\">est\u00e1gio cr\u00edtico.\u00a0<\/a><\/p>\n<h1>A solu\u00e7\u00e3o<\/h1>\n<p>Com base nesses <a href=\"https:\/\/semapi.com.br\/en\/da-ordem-de-servico-ao-pedido-um-case-de-eficiencia-entre-manutencao-e-suprimentos\/\">resultados<\/a>, foi emitido um laudo t\u00e9cnico orientando a\u00a0substitui\u00e7\u00e3o preventiva\u00a0do componente. A recomenda\u00e7\u00e3o n\u00e3o se tratava apenas de trocar um rolamento, mas de evitar um cen\u00e1rio de parada inesperada que, dependendo do momento da opera\u00e7\u00e3o, poderia significar entre quatro e sete horas de indisponibilidade. Em uma m\u00e1quina com alta capacidade produtiva, essa diferen\u00e7a representa muito mais do que tempo perdido: representa dinheiro.<\/p>\n<p>A m\u00e1quina em quest\u00e3o possui uma <a href=\"https:\/\/semapi.com.br\/en\/mais-do-que-relatorios-como-interpretar-a-saude-dos-equipamentos-em-tempo-real\/\">produ\u00e7\u00e3o<\/a> te\u00f3rica pr\u00f3xima de 115 toneladas por dia.\u00a0Isso significa que uma parada acidental de quatro horas poderia gerar perdas diretas de aproximadamente R$ 163 mil.<\/p>\n<h1>Sem preju\u00edzo<\/h1>\n<p>Gra\u00e7as ao monitoramento cont\u00ednuo\u00a0da equipe da SEMAPI, esse preju\u00edzo n\u00e3o aconteceu.\u00a0Em meio ao acompanhamento\u00a0peri\u00f3dico, os n\u00edveis de vibra\u00e7\u00e3o continuaram aumentando, confirmando o avan\u00e7o do defeito. A equipe de manuten\u00e7\u00e3o, de forma estrat\u00e9gica, decidiu aproveitar uma\u00a0parada de produ\u00e7\u00e3o j\u00e1 programada para realizar a troca do rolamento, evitando qualquer impacto no cronograma ou no volume fabricado.<\/p>\n<p>Ao transformar uma falha iminente em uma <a href=\"https:\/\/semapi.com.br\/en\/mantec\/\">interven\u00e7\u00e3o\u00a0n\u00e3o planejada,<\/a> a empresa preservou a disponibilidade do ativo, manteve a produ\u00e7\u00e3o est\u00e1vel e refor\u00e7ou a cultura de confiabilidade. O caso demonstra a import\u00e2ncia da manuten\u00e7\u00e3o preditiva como ferramenta de tomada de decis\u00e3o: ela oferece tempo, precis\u00e3o e seguran\u00e7a para evitar que pequenos sinais se tornem grandes perdas.<\/p>\n<p>Mais do que detectar falhas, a an\u00e1lise de vibra\u00e7\u00e3o permitiu agir no momento certo, protegendo o equipamento e garantindo que a opera\u00e7\u00e3o\u00a0seguisse\u00a0sem interrup\u00e7\u00f5es. <a href=\"https:\/\/semapi.com.br\/en\/fale-conosco\/\">Este \u00e9 um exemplo claro<\/a> de como a integra\u00e7\u00e3o entre monitoramento, engenharia e produ\u00e7\u00e3o gera resultados concretos,\u00a0tanto na efici\u00eancia quanto no desempenho financeiro da planta.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em ambientes industriais de alta performance, como o setor papeleiro, pequenas anomalias podem evoluir rapidamente para grandes problemas. Foi exatamente isso que a manuten\u00e7\u00e3o preditiva da SEMAPI conseguiu evitar neste caso: a falha de um rolamento cr\u00edtico em uma m\u00e1quina de papel, um evento que poderia gerar aproximadamente 7 horas de parada n\u00e3o planejada e [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":4815,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":11,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/en\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/en\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Em ambientes industriais de alta performance, como o setor papeleiro, pequenas anomalias podem evoluir rapidamente para grandes problemas. Foi exatamente isso que a manuten\u00e7\u00e3o preditiva da SEMAPI conseguiu evitar neste caso: a falha de um rolamento cr\u00edtico em uma m\u00e1quina de papel, um evento que poderia gerar aproximadamente 7 horas de parada n\u00e3o planejada e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/en\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T17:11:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo\",\"datePublished\":\"2025-11-18T17:11:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/analysys2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/\",\"name\":\"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/analysys2.jpg\",\"datePublished\":\"2025-11-18T17:11:24+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/analysys2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/analysys2.jpg\",\"width\":1024,\"height\":576,\"caption\":\"analysys\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/en\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/","og_locale":"en_US","og_type":"article","og_title":"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI","og_description":"Em ambientes industriais de alta performance, como o setor papeleiro, pequenas anomalias podem evoluir rapidamente para grandes problemas. Foi exatamente isso que a manuten\u00e7\u00e3o preditiva da SEMAPI conseguiu evitar neste caso: a falha de um rolamento cr\u00edtico em uma m\u00e1quina de papel, um evento que poderia gerar aproximadamente 7 horas de parada n\u00e3o planejada e [&hellip;]","og_url":"https:\/\/semapi.com.br\/en\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/","og_site_name":"SEMAPI","article_published_time":"2025-11-18T17:11:24+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo","datePublished":"2025-11-18T17:11:24+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/"},"wordCount":464,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","articleSection":["sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/","url":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/","name":"SEMAPI identifica falha cr\u00edtica e evita 7 horas de parada e R$ 163 mil em preju\u00edzo - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","datePublished":"2025-11-18T17:11:24+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/semapi-identifica-falha-critica-e-evita-7-horas-de-parada-e-r-163-mil-em-prejuizo\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/11\/analysys2.jpg","width":1024,"height":576,"caption":"analysys"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/en\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/comments?post=4813"}],"version-history":[{"count":1,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4813\/revisions"}],"predecessor-version":[{"id":4814,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4813\/revisions\/4814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media\/4815"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media?parent=4813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/categories?post=4813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/tags?post=4813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}