{"id":4544,"date":"2025-09-15T10:37:41","date_gmt":"2025-09-15T13:37:41","guid":{"rendered":"https:\/\/semapi.com.br\/?p=4544"},"modified":"2025-10-07T15:44:28","modified_gmt":"2025-10-07T18:44:28","slug":"a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/en\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/","title":{"rendered":"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4544\" class=\"elementor elementor-4544\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-769194c e-flex e-con-boxed e-con e-parent\" data-id=\"769194c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6e2d53 elementor-widget elementor-widget-text-editor\" data-id=\"f6e2d53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Na ind\u00fastria de papel, cada minuto de produ\u00e7\u00e3o \u00e9 valioso. Por isso, a\u00a0<\/span><a href=\"https:\/\/semapi.com.br\/manutencao\/\"><b><span data-contrast=\"none\">manuten\u00e7\u00e3o preditiva<\/span><\/b><\/a><span data-contrast=\"none\">\u00a0tem um papel essencial na preven\u00e7\u00e3o de falhas e na garantia da continuidade operacional. Um caso recente envolvendo a\u00a0<\/span><b><span data-contrast=\"none\">m\u00e1quina de papel de um de nossos clientes<\/span><\/b><span data-contrast=\"none\">\u00a0ilustra perfeitamente o valor dessa abordagem.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Durante uma\u00a0<\/span><b><span data-contrast=\"none\">inspe\u00e7\u00e3o de rotina<\/span><\/b><span data-contrast=\"none\">\u00a0na \u00e1rea de prensas, nossa equipe identificou um\u00a0<\/span><b><span data-contrast=\"none\">aumento significativo nos n\u00edveis de vibra\u00e7\u00e3o<\/span><\/b><span data-contrast=\"none\">\u00a0no rolamento\u00a0<\/span><span data-contrast=\"none\">. A an\u00e1lise de vibra\u00e7\u00e3o no par\u00e2metro de acelera\u00e7\u00e3o indicou uma falha em est\u00e1gio inicial, que foi confirmada com uma\u00a0<\/span><b><span data-contrast=\"none\">inspe\u00e7\u00e3o visual<\/span><\/b><span data-contrast=\"none\">, revelando:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Vazamento de graxa escura e \u00e1gua pelo mancal;<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><ul><li aria-setsize=\"-1\" data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559683&quot;:0,&quot;335559684&quot;:-2,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;hybridMultilevel&quot;}\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"none\">Veda\u00e7\u00f5es danificadas.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"none\">Imediatamente, emitimos um\u00a0<\/span><b><span data-contrast=\"none\">laudo t\u00e9cnico<\/span><\/b><span data-contrast=\"none\">\u00a0recomendando a substitui\u00e7\u00e3o do rolamento e das veda\u00e7\u00f5es. A equipe de planejamento do cliente, aproveitando uma\u00a0<\/span><b><span data-contrast=\"none\">parada programada para troca de fabrica\u00e7\u00e3o<\/span><\/b><span data-contrast=\"none\">, realizou a interven\u00e7\u00e3o necess\u00e1ria sem impactar a produ\u00e7\u00e3o.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><h2><b><span data-contrast=\"none\">Resultados:<\/span><\/b><\/h2><ol><li><span data-contrast=\"none\">Substitui\u00e7\u00e3o do rolamento e veda\u00e7\u00f5es sem parada emergencial;<\/span><\/li><li><span data-contrast=\"none\">Evitou-se danos maiores a outros componentes da m\u00e1quina;<\/span><\/li><li><span data-contrast=\"none\">Manteve-se a <\/span><b><span data-contrast=\"none\">disponibilidade operacional<\/span><\/b><span data-contrast=\"none\">\u00a0e a\u00a0<\/span><b><span data-contrast=\"none\">confiabilidade do equipamento.<\/span><\/b><\/li><\/ol><p>\u00a0<\/p><p><span data-contrast=\"none\">Este caso refor\u00e7a como a\u00a0<\/span><b><span data-contrast=\"none\">manuten\u00e7\u00e3o preditiva<\/span><\/b><span data-contrast=\"none\">\u00a0vai al\u00e9m do monitoramento: ela fornece aprendizados valiosos para a\u00a0<\/span><b><span data-contrast=\"none\">tomada de decis\u00f5es assertivas<\/span><\/b><span data-contrast=\"none\">, garantindo que as interven\u00e7\u00f5es sejam realizadas no momento certo, com o m\u00ednimo de impacto na produ\u00e7\u00e3o.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Na <a href=\"https:\/\/semapi.com.br\/\">SEMAPI<\/a>, transformamos dados em a\u00e7\u00f5es preventivas que protegem seus ativos e seu neg\u00f3cio.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335557856&quot;:16777215,&quot;335559738&quot;:240,&quot;335559739&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fe809a e-flex e-con-boxed e-con e-parent\" data-id=\"1fe809a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25b087b elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"25b087b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Cs Felipe\" style=\"background-image: url(&#039;https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/Cs-Felipe-2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"cs felipe\" style=\"background-image: url(&#039;https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/cs-felipe-1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"CS Felipe\" style=\"background-image: url(&#039;https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/CS-Felipe-3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3b6a26 e-flex e-con-boxed e-con e-parent\" data-id=\"c3b6a26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adcd6c8 elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"adcd6c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tWhatsApp\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Na ind\u00fastria de papel, cada minuto de produ\u00e7\u00e3o \u00e9 valioso. Por isso, a\u00a0manuten\u00e7\u00e3o preditiva\u00a0tem um papel essencial na preven\u00e7\u00e3o de falhas e na garantia da continuidade operacional. Um caso recente envolvendo a\u00a0m\u00e1quina de papel de um de nossos clientes\u00a0ilustra perfeitamente o valor dessa abordagem.\u00a0 Durante uma\u00a0inspe\u00e7\u00e3o de rotina\u00a0na \u00e1rea de prensas, nossa equipe identificou um\u00a0aumento [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":4602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":3,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","author_info":{"display_name":"B\u00e1rbarah Andrade Fernandes Machado","author_link":"https:\/\/semapi.com.br\/en\/author\/bafernandes\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/en\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Na ind\u00fastria de papel, cada minuto de produ\u00e7\u00e3o \u00e9 valioso. Por isso, a\u00a0manuten\u00e7\u00e3o preditiva\u00a0tem um papel essencial na preven\u00e7\u00e3o de falhas e na garantia da continuidade operacional. Um caso recente envolvendo a\u00a0m\u00e1quina de papel de um de nossos clientes\u00a0ilustra perfeitamente o valor dessa abordagem.\u00a0 Durante uma\u00a0inspe\u00e7\u00e3o de rotina\u00a0na \u00e1rea de prensas, nossa equipe identificou um\u00a0aumento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/en\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T13:37:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T18:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"B\u00e1rbarah Andrade Fernandes Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/\"},\"author\":{\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\"},\"headline\":\"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o\",\"datePublished\":\"2025-09-15T13:37:41+00:00\",\"dateModified\":\"2025-10-07T18:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/nan2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/\",\"name\":\"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/nan2.jpg\",\"datePublished\":\"2025-09-15T13:37:41+00:00\",\"dateModified\":\"2025-10-07T18:44:28+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/nan2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/nan2.jpg\",\"width\":1024,\"height\":535,\"caption\":\"nan\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/b10402762827e92906bc8e022312db3e\",\"name\":\"B\u00e1rbarah Andrade Fernandes Machado\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/author\\\/bafernandes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/en\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/","og_locale":"en_US","og_type":"article","og_title":"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI","og_description":"Na ind\u00fastria de papel, cada minuto de produ\u00e7\u00e3o \u00e9 valioso. Por isso, a\u00a0manuten\u00e7\u00e3o preditiva\u00a0tem um papel essencial na preven\u00e7\u00e3o de falhas e na garantia da continuidade operacional. Um caso recente envolvendo a\u00a0m\u00e1quina de papel de um de nossos clientes\u00a0ilustra perfeitamente o valor dessa abordagem.\u00a0 Durante uma\u00a0inspe\u00e7\u00e3o de rotina\u00a0na \u00e1rea de prensas, nossa equipe identificou um\u00a0aumento [&hellip;]","og_url":"https:\/\/semapi.com.br\/en\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/","og_site_name":"SEMAPI","article_published_time":"2025-09-15T13:37:41+00:00","article_modified_time":"2025-10-07T18:44:28+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","type":"image\/jpeg"}],"author":"B\u00e1rbarah Andrade Fernandes Machado","twitter_card":"summary_large_image","twitter_misc":{"Written by":"B\u00e1rbarah Andrade Fernandes Machado","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/"},"author":{"name":"B\u00e1rbarah Andrade Fernandes Machado","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e"},"headline":"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o","datePublished":"2025-09-15T13:37:41+00:00","dateModified":"2025-10-07T18:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/"},"wordCount":269,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","articleSection":["sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/","url":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/","name":"A 3mm de uma parada milion\u00e1ria: como salvamos uma m\u00e1quina de papel com um laudo de vibra\u00e7\u00e3o - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","datePublished":"2025-09-15T13:37:41+00:00","dateModified":"2025-10-07T18:44:28+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/a-3mm-de-uma-parada-milionaria-como-salvamos-uma-maquina-de-papel-com-um-laudo-de-vibracao\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/09\/nan2.jpg","width":1024,"height":535,"caption":"nan"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/b10402762827e92906bc8e022312db3e","name":"B\u00e1rbarah Andrade Fernandes Machado","url":"https:\/\/semapi.com.br\/en\/author\/bafernandes\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":17,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":4678,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4544\/revisions\/4678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media\/4602"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}