{"id":4223,"date":"2025-07-31T09:04:17","date_gmt":"2025-07-31T12:04:17","guid":{"rendered":"https:\/\/semapi.com.br\/?p=4223"},"modified":"2025-07-31T09:04:17","modified_gmt":"2025-07-31T12:04:17","slug":"confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/en\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/","title":{"rendered":"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva"},"content":{"rendered":"<p><span data-contrast=\"auto\">Em ambientes industriais, onde a confiabilidade dos equipamentos \u00e9 fundamental, antecipar falhas pode fazer toda a diferen\u00e7a. \u00c9 nesse contexto que a ferrografia se destaca como <strong>uma t\u00e9cnica indispens\u00e1vel<\/strong> na <a href=\"https:\/\/semapi.com.br\/en\/por-que-adotar-a-deteccao-de-vazamento-de-gases-veja-as-vantagens\/\">manuten\u00e7\u00e3o preditiva.<\/a><\/span><\/p>\n<p><span data-contrast=\"auto\">Ao analisar part\u00edculas presentes nos lubrificantes, revela n\u00e3o apenas o estado interno das m\u00e1quinas, mas tamb\u00e9m orienta decis\u00f5es estrat\u00e9gicas <strong>sobre interven\u00e7\u00f5es e trocas de componentes.<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<h1><span data-contrast=\"auto\">O que \u00e9 ferrografia?<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A ferrografia \u00e9 uma t\u00e9cnica laboratorial baseada no estudo tribol\u00f3gico \u2014 a ci\u00eancia que investiga a intera\u00e7\u00e3o entre superf\u00edcies em movimento. Por meio da an\u00e1lise de part\u00edculas contidas em amostras de \u00f3leos lubrificantes, \u00e9 poss\u00edvel <strong>identificar o tipo, o grau e a origem do desgaste<\/strong> dos <a href=\"https:\/\/semapi.com.br\/en\/manutencao-preditiva-em-baterias-entenda-como-funciona-o-processo-e-a-sua-importancia\/\">componentes internos<\/a> das m\u00e1quinas.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mas n\u00e3o se trata apenas de metais: part\u00edculas como areia, fuligem, borra e fibras org\u00e2nicas tamb\u00e9m s\u00e3o analisadas, oferecendo uma vis\u00e3o completa sobre contamina\u00e7\u00f5es e desempenho do lubrificante.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">Vantagens!<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">Confira as principais <a href=\"https:\/\/semapi.com.br\/en\/como-funciona-o-diagnostico-em-valvulas-de-controle-entenda-o-processo\/\">vantagens<\/a> de adotar essa t\u00e9cnica em sua rotina de manuten\u00e7\u00e3o:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li><span data-contrast=\"auto\"><strong>Diagn\u00f3stico preciso do desgaste:<\/strong> A ferrografia identifica n\u00e3o s\u00f3 a presen\u00e7a de desgaste, mas tamb\u00e9m sua natureza, gravidade e poss\u00edvel origem (como abras\u00e3o, corros\u00e3o ou esfolia\u00e7\u00e3o).<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Tomada de decis\u00e3o mais segura:<\/strong> Com base nos resultados, \u00e9 poss\u00edvel definir a urg\u00eancia e o tipo de interven\u00e7\u00e3o necess\u00e1ria, evitando paradas imprevistas e otimizando os recursos da manuten\u00e7\u00e3o.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Redu\u00e7\u00e3o de custos:<\/strong> Ao detectar falhas em est\u00e1gio inicial, a t\u00e9cnica evita danos maiores e diminui os gastos com trocas prematuras de pe\u00e7as e equipamentos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Aumento da vida \u00fatil dos equipamentos:<\/strong> A an\u00e1lise cont\u00ednua e precisa permite ajustes preventivos e melhora a performance dos sistemas, prolongando sua durabilidade.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<h1><span data-contrast=\"auto\">Tipos de an\u00e1lise dispon\u00edveis<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A ferrografia pode ser aplicada de duas formas principais:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<ul>\n<li><span data-contrast=\"auto\"><strong>Exame Anal\u00edtico:<\/strong> Foca na identifica\u00e7\u00e3o das part\u00edculas e suas caracter\u00edsticas, avaliando tipo de desgaste, morfologia e poss\u00edveis contaminantes. Ideal para entender a origem e a gravidade do problema.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\"><strong>Exame Quantitativo:<\/strong> Mede o volume e o tamanho das part\u00edculas (acima ou abaixo de 5 \u00b5m), gerando dados para an\u00e1lises de tend\u00eancia. \u00c9 uma leitura mais direta e \u00fatil para monitoramento cont\u00ednuo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<\/ul>\n<p>Quer garantir mais confiabilidade e efici\u00eancia na sua manuten\u00e7\u00e3o? A SEMAPI \u00e9 especialista em t\u00e9cnicas preditivas como a ferrografia, ajudando empresas a antecipar falhas e reduzir custos com precis\u00e3o.\u00a0 <a href=\"https:\/\/semapi.com.br\/en\/fale-conosco\/\">Fale com nossos especialistas<\/a> e saiba como implementar essa solu\u00e7\u00e3o na sua opera\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em ambientes industriais, onde a confiabilidade dos equipamentos \u00e9 fundamental, antecipar falhas pode fazer toda a diferen\u00e7a. \u00c9 nesse contexto que a ferrografia se destaca como uma t\u00e9cnica indispens\u00e1vel na manuten\u00e7\u00e3o preditiva. Ao analisar part\u00edculas presentes nos lubrificantes, revela n\u00e3o apenas o estado interno das m\u00e1quinas, mas tamb\u00e9m orienta decis\u00f5es estrat\u00e9gicas sobre interven\u00e7\u00f5es e trocas [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":4229,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":26,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/en\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/en\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Em ambientes industriais, onde a confiabilidade dos equipamentos \u00e9 fundamental, antecipar falhas pode fazer toda a diferen\u00e7a. \u00c9 nesse contexto que a ferrografia se destaca como uma t\u00e9cnica indispens\u00e1vel na manuten\u00e7\u00e3o preditiva. Ao analisar part\u00edculas presentes nos lubrificantes, revela n\u00e3o apenas o estado interno das m\u00e1quinas, mas tamb\u00e9m orienta decis\u00f5es estrat\u00e9gicas sobre interven\u00e7\u00f5es e trocas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/en\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T12:04:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva\",\"datePublished\":\"2025-07-31T12:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/\"},\"wordCount\":439,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ferro2.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/\",\"name\":\"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ferro2.jpg\",\"datePublished\":\"2025-07-31T12:04:17+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ferro2.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ferro2.jpg\",\"width\":1024,\"height\":535,\"caption\":\"ferro\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/en\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/","og_locale":"en_US","og_type":"article","og_title":"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI","og_description":"Em ambientes industriais, onde a confiabilidade dos equipamentos \u00e9 fundamental, antecipar falhas pode fazer toda a diferen\u00e7a. \u00c9 nesse contexto que a ferrografia se destaca como uma t\u00e9cnica indispens\u00e1vel na manuten\u00e7\u00e3o preditiva. Ao analisar part\u00edculas presentes nos lubrificantes, revela n\u00e3o apenas o estado interno das m\u00e1quinas, mas tamb\u00e9m orienta decis\u00f5es estrat\u00e9gicas sobre interven\u00e7\u00f5es e trocas [&hellip;]","og_url":"https:\/\/semapi.com.br\/en\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/","og_site_name":"SEMAPI","article_published_time":"2025-07-31T12:04:17+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva","datePublished":"2025-07-31T12:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/"},"wordCount":439,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","articleSection":["sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/","url":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/","name":"Confira 4 vantagens da ferrografia que v\u00e3o transformar sua manuten\u00e7\u00e3o preditiva - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","datePublished":"2025-07-31T12:04:17+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/confira-4-vantagens-da-ferrografia-que-vao-transformar-sua-manutencao-preditiva\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/07\/ferro2.jpg","width":1024,"height":535,"caption":"ferro"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/en\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/comments?post=4223"}],"version-history":[{"count":4,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4223\/revisions"}],"predecessor-version":[{"id":4228,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/4223\/revisions\/4228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media\/4229"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media?parent=4223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/categories?post=4223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/tags?post=4223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}