{"id":3791,"date":"2025-05-30T09:09:05","date_gmt":"2025-05-30T12:09:05","guid":{"rendered":"https:\/\/semapi.com.br\/?p=3791"},"modified":"2025-05-30T09:09:05","modified_gmt":"2025-05-30T12:09:05","slug":"o-que-significa-termografia-entenda-como-funciona","status":"publish","type":"post","link":"https:\/\/semapi.com.br\/en\/o-que-significa-termografia-entenda-como-funciona\/","title":{"rendered":"O que significa termografia? Entenda como funciona"},"content":{"rendered":"<p><span data-contrast=\"auto\">Quando falamos em confiabilidade e efici\u00eancia na opera\u00e7\u00e3o industrial, <a href=\"https:\/\/semapi.com.br\/en\/o-que-e-analise-de-vibracao-e-como-funciona\/\">a manuten\u00e7\u00e3o preditiva<\/a> ocupa um papel central \u2014 e uma das t\u00e9cnicas mais poderosas dentro dessa abordagem \u00e9 a Termografia. Com esse processo, \u00e9 poss\u00edvel <strong>identificar problemas invis\u00edveis a olho nu<\/strong> e tomar decis\u00f5es assertivas antes que falhas comprometam a produtividade.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A termografia, ou inspe\u00e7\u00e3o termogr\u00e1fica, \u00e9 uma t\u00e9cnica <a href=\"https:\/\/semapi.com.br\/en\/dia-da-industria-manutencao-preditiva-e-investimento-nao-custo\/\">de manuten\u00e7\u00e3o preditiva<\/a> que utiliza c\u00e2meras especiais para detectar a radia\u00e7\u00e3o infravermelha emitida pelos objetos. Em outras palavras, a t\u00e9cnica transforma varia\u00e7\u00f5es de temperatura em imagens \u2014 chamadas termogramas \u2014 que mostram exatamente <strong>onde h\u00e1 pontos de calor anormal.<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">Essas imagens t\u00e9rmicas <strong>revelam padr\u00f5es de distribui\u00e7\u00e3o de calor<\/strong> e <a href=\"https:\/\/semapi.com.br\/en\/dia-da-industria-entenda-o-papel-da-semapi-na-seguranca-de-ambientes-criticos\/\">permitem identificar problemas<\/a> como aquecimento excessivo, curtos-circuitos iminentes, falhas em componentes mec\u00e2nicos ou el\u00e9tricos, entre outros.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h1><span data-contrast=\"auto\">Benefits<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A inspe\u00e7\u00e3o termogr\u00e1fica apresenta <strong>in\u00fameras vantagens operacionais:<\/strong><\/span><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><span data-contrast=\"auto\">An\u00e1lise sem contato f\u00edsico: proporciona seguran\u00e7a ao t\u00e9cnico, sem afetar a precis\u00e3o da medi\u00e7\u00e3o;<\/span><\/li>\n<li><span data-contrast=\"auto\">Sem necessidade de interromper a produ\u00e7\u00e3o: a an\u00e1lise pode ser feita com os equipamentos em funcionamento;<\/span><\/li>\n<li><span data-contrast=\"auto\">Redu\u00e7\u00e3o da manuten\u00e7\u00e3o corretiva: permite identificar falhas antes que se tornem problemas graves.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Economia de energia: ao detectar sobrecargas e falhas ocultas, contribui para o uso eficiente da energia el\u00e9trica;\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Aumento da vida \u00fatil de equipamentos: reduz desgastes prematuros e melhora o desempenho geral;<\/span><\/li>\n<li><span data-contrast=\"auto\">Maior produtividade e efici\u00eancia dos programas de manuten\u00e7\u00e3o: torna o processo mais \u00e1gil, preciso e confi\u00e1vel;<\/span><\/li>\n<li><span data-contrast=\"auto\">Redu\u00e7\u00e3o de estoque de pe\u00e7as sobressalentes: evita trocas desnecess\u00e1rias;\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Preven\u00e7\u00e3o de inc\u00eandios: ao detectar aquecimentos anormais em sistemas el\u00e9tricos, contribui diretamente para a seguran\u00e7a da planta;\u00a0<\/span>\n<p><figure id=\"attachment_3799\" aria-describedby=\"caption-attachment-3799\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-3799 size-large\" title=\"termografia\" src=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6-1024x576.jpg\" alt=\"termografia\" width=\"800\" height=\"450\" srcset=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6-1024x576.jpg 1024w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6-300x169.jpg 300w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6-768x432.jpg 768w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6-18x10.jpg 18w, https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia6.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3799\" class=\"wp-caption-text\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0A termografia na pr\u00e1tica<\/em><\/figcaption><\/figure><\/li>\n<\/ul>\n<h1><span data-contrast=\"auto\">Aplica\u00e7\u00e3o <\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h1>\n<p><span data-contrast=\"auto\">A versatilidade da inspe\u00e7\u00e3o termogr\u00e1fica faz com que ela seja amplamente <strong>utilizada em diferentes setores<\/strong>:<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"auto\">Setor eletroeletr\u00f4nico<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">An\u00e1lise de quadros el\u00e9tricos, circuitos, nobreaks, cabines de energia e subesta\u00e7\u00f5es. <\/span><span data-contrast=\"auto\">Verifica\u00e7\u00e3o de linhas de alta tens\u00e3o e instala\u00e7\u00f5es el\u00e9tricas industriais.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"auto\">Setor mec\u00e2nico<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Avalia\u00e7\u00e3o de equipamentos est\u00e1ticos e din\u00e2micos, permitindo identificar superaquecimentos e outros sinais de falha.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"auto\">Constru\u00e7\u00e3o civil<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Inspe\u00e7\u00f5es em sistemas de aquecimento e refrigera\u00e7\u00e3o, infiltra\u00e7\u00f5es, isolamentos t\u00e9rmicos, pontes e estruturas de concreto.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"auto\">Ind\u00fastria automobil\u00edstica<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Monitoramento de freios, sistemas de refrigera\u00e7\u00e3o e comportamento de pneus.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"auto\">Transporte ferrovi\u00e1rio<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Avalia\u00e7\u00e3o de sistemas de freios, esfor\u00e7o nos trilhos, rodas de composi\u00e7\u00f5es e infraestrutura de via permanente.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p>A termografia ainda pode ser aplicada em:<\/p>\n<ul>\n<li><span data-contrast=\"auto\">Agricultura: an\u00e1lise de umidade do solo;<\/span><\/li>\n<li><span data-contrast=\"auto\">Linhas de transmiss\u00e3o e cabos de comunica\u00e7\u00e3o;<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Inspe\u00e7\u00e3o de tubula\u00e7\u00f5es e tanques;<\/span><\/li>\n<li><span data-contrast=\"auto\">Embarca\u00e7\u00f5es e infraestrutura portu\u00e1ria;<\/span><\/li>\n<li><span data-contrast=\"auto\">Monitoramento de processos industriais e preven\u00e7\u00e3o de inc\u00eandios;<\/span><\/li>\n<li><span data-contrast=\"auto\">Localiza\u00e7\u00e3o de pessoas por for\u00e7as de seguran\u00e7a;\u00a0<\/span><\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">A termografia \u00e9 muito mais do que uma t\u00e9cnica de medi\u00e7\u00e3o de temperatura \u2014 \u00e9 uma <strong>t\u00e9cnica que fortalece a manuten\u00e7\u00e3o preditiva<\/strong>, contribuindo para a efici\u00eancia operacional, seguran\u00e7a e sustentabilidade dos processos industriais.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Empresas que investem em inspe\u00e7\u00f5es termogr\u00e1ficas ganham em agilidade na tomada de decis\u00f5es, preven\u00e7\u00e3o de falhas cr\u00edticas e maior controle sobre seus ativos. <a href=\"https:\/\/semapi.com.br\/en\/fale-conosco\/\">Contact Semapi<\/a> e garanta essa efici\u00eancia. <\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Quando falamos em confiabilidade e efici\u00eancia na opera\u00e7\u00e3o industrial, a manuten\u00e7\u00e3o preditiva ocupa um papel central \u2014 e uma das t\u00e9cnicas mais poderosas dentro dessa abordagem \u00e9 a Termografia. Com esse processo, \u00e9 poss\u00edvel identificar problemas invis\u00edveis a olho nu e tomar decis\u00f5es assertivas antes que falhas comprometam a produtividade.\u00a0 A termografia, ou inspe\u00e7\u00e3o termogr\u00e1fica, [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":3798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"iawp_total_views":209,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_src":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","author_info":{"display_name":"marketing","author_link":"https:\/\/semapi.com.br\/en\/author\/marketing\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que significa termografia? Entenda como funciona - SEMAPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semapi.com.br\/en\/o-que-significa-termografia-entenda-como-funciona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que significa termografia? Entenda como funciona - SEMAPI\" \/>\n<meta property=\"og:description\" content=\"Quando falamos em confiabilidade e efici\u00eancia na opera\u00e7\u00e3o industrial, a manuten\u00e7\u00e3o preditiva ocupa um papel central \u2014 e uma das t\u00e9cnicas mais poderosas dentro dessa abordagem \u00e9 a Termografia. Com esse processo, \u00e9 poss\u00edvel identificar problemas invis\u00edveis a olho nu e tomar decis\u00f5es assertivas antes que falhas comprometam a produtividade.\u00a0 A termografia, ou inspe\u00e7\u00e3o termogr\u00e1fica, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semapi.com.br\/en\/o-que-significa-termografia-entenda-como-funciona\/\" \/>\n<meta property=\"og:site_name\" content=\"SEMAPI\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T12:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/\"},\"author\":{\"name\":\"marketing\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\"},\"headline\":\"O que significa termografia? Entenda como funciona\",\"datePublished\":\"2025-05-30T12:09:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/termografia2-1.jpg\",\"articleSection\":[\"sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/\",\"name\":\"O que significa termografia? Entenda como funciona - SEMAPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/termografia2-1.jpg\",\"datePublished\":\"2025-05-30T12:09:05+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/o-que-significa-termografia-entenda-como-funciona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/termografia2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/termografia2-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"termografia ()\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#website\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"name\":\"SEMAPI\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semapi.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#organization\",\"name\":\"SEMAPI\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"contentUrl\":\"https:\\\/\\\/semapi.com.br\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Semapi-Logo.png\",\"width\":179,\"height\":56,\"caption\":\"SEMAPI\"},\"image\":{\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semapi.com.br\\\/#\\\/schema\\\/person\\\/840f49733c5d3ebb2bbd58c9c794eca4\",\"name\":\"marketing\",\"url\":\"https:\\\/\\\/semapi.com.br\\\/en\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que significa termografia? Entenda como funciona - SEMAPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semapi.com.br\/en\/o-que-significa-termografia-entenda-como-funciona\/","og_locale":"en_US","og_type":"article","og_title":"O que significa termografia? Entenda como funciona - SEMAPI","og_description":"Quando falamos em confiabilidade e efici\u00eancia na opera\u00e7\u00e3o industrial, a manuten\u00e7\u00e3o preditiva ocupa um papel central \u2014 e uma das t\u00e9cnicas mais poderosas dentro dessa abordagem \u00e9 a Termografia. Com esse processo, \u00e9 poss\u00edvel identificar problemas invis\u00edveis a olho nu e tomar decis\u00f5es assertivas antes que falhas comprometam a produtividade.\u00a0 A termografia, ou inspe\u00e7\u00e3o termogr\u00e1fica, [&hellip;]","og_url":"https:\/\/semapi.com.br\/en\/o-que-significa-termografia-entenda-como-funciona\/","og_site_name":"SEMAPI","article_published_time":"2025-05-30T12:09:05+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","type":"image\/jpeg"}],"author":"marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/#article","isPartOf":{"@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/"},"author":{"name":"marketing","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4"},"headline":"O que significa termografia? Entenda como funciona","datePublished":"2025-05-30T12:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/"},"wordCount":562,"publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","articleSection":["sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/","url":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/","name":"O que significa termografia? Entenda como funciona - SEMAPI","isPartOf":{"@id":"https:\/\/semapi.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/#primaryimage"},"image":{"@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/#primaryimage"},"thumbnailUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","datePublished":"2025-05-30T12:09:05+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/o-que-significa-termografia-entenda-como-funciona\/#primaryimage","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2025\/05\/termografia2-1.jpg","width":1280,"height":720,"caption":"termografia ()"},{"@type":"WebSite","@id":"https:\/\/semapi.com.br\/#website","url":"https:\/\/semapi.com.br\/","name":"SEMAPI","description":"","publisher":{"@id":"https:\/\/semapi.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semapi.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semapi.com.br\/#organization","name":"SEMAPI","url":"https:\/\/semapi.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","contentUrl":"https:\/\/semapi.com.br\/wp-content\/uploads\/2020\/02\/Semapi-Logo.png","width":179,"height":56,"caption":"SEMAPI"},"image":{"@id":"https:\/\/semapi.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semapi.com.br\/#\/schema\/person\/840f49733c5d3ebb2bbd58c9c794eca4","name":"marketing","url":"https:\/\/semapi.com.br\/en\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/3791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/comments?post=3791"}],"version-history":[{"count":9,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/3791\/revisions"}],"predecessor-version":[{"id":3802,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/posts\/3791\/revisions\/3802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media\/3798"}],"wp:attachment":[{"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/media?parent=3791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/categories?post=3791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semapi.com.br\/en\/wp-json\/wp\/v2\/tags?post=3791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}